{"id":232,"date":"2016-06-02T19:30:48","date_gmt":"2016-06-02T19:30:48","guid":{"rendered":"https:\/\/advancedsofttissuerelease.com\/de-quervain-s\/"},"modified":"2022-02-21T15:38:14","modified_gmt":"2022-02-21T22:38:14","slug":"de-quervains-tenosynovitis-symptome-behandlung-2","status":"publish","type":"page","link":"https:\/\/advancedsofttissuerelease.com\/de\/de-quervains-tenosynovitis-symptoms-treatment\/","title":{"rendered":"Tenosynovitis de Quervain: Symptome und Behandlung\u00a0"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"232\" class=\"elementor elementor-232\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-717d1e57 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"717d1e57\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4336a5cc\" data-id=\"4336a5cc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-567e0142 elementor-widget elementor-widget-text-editor\" data-id=\"567e0142\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1 class=\"p1\"><strong><span style=\"color: #696969;\"><span class=\"s1\">Tenosynovitis de Quervain: Symptome &amp;\u00a0<\/span><\/span><span style=\"color: #696969;\"><span style=\"caret-color: #696969;\">Behandlung\u00a0<\/span><\/span><\/strong><\/h1><h2><strong><span style=\"color: #696969;\"><span class=\"s2\">Was ist die Sehnenscheidenentz\u00fcndung von De Quervain?<\/span><\/span><\/strong><\/h2><p class=\"p1\"><span style=\"color: #696969;\"><span class=\"s2\">Die Tenosynovitis-Krankheit von De Quervain ist eine schmerzhafte Erkrankung, die durch eine Entz\u00fcndung der Sehnen auf der Daumenseite des Handgelenks verursacht wird. Greifen, eine Faust machen oder mit den H\u00e4nden arbeiten kann Symptome der De-Quervain-Krankheit hervorrufen. Die Tenosynovitis-Krankheit von De Quervain betrifft Frauen 8 von 10 Mal h\u00e4ufiger als M\u00e4nner und kann nach einer Schwangerschaft auftreten.<\/span><\/span><\/p><h2 class=\"p2\"><strong><span style=\"color: #696969; font-family: 'Helvetica Neue', Helvetica, Arial, sans-serif; font-size: 30px; line-height: 1.1;\">Symptome von De Quervains T<\/span><span style=\"color: #696969; font-family: 'Helvetica Neue', Helvetica, Arial, sans-serif; font-size: 30px; line-height: 1.1;\">Enosynovitis<\/span><\/strong><\/h2><ol><li class=\"p1\"><span style=\"color: #696969;\"><span class=\"s2\">Schwierigkeiten, Daumen oder Handgelenk beim Greifen zu bewegen<\/span><\/span><\/li><li class=\"p1\"><span style=\"color: #696969;\"><span class=\"s2\">Schmerzen in der N\u00e4he der Daumenbasis<\/span><\/span><\/li><li class=\"p1\"><span style=\"color: #696969;\"><span class=\"s2\">Stoppendes oder klemmendes Gef\u00fchl beim Bewegen von Daumen oder Handgelenk<\/span><\/span><\/li><\/ol><h2 class=\"p1\"><strong><span style=\"color: #696969;\"><span class=\"s1\">Behandlung der Sehnenscheidenentz\u00fcndung von De Quervain<\/span><\/span><\/strong><\/h2><p>ASTR-Leckereien<span class=\"Apple-converted-space\"> <span style=\"color: #696969;\"><span class=\"s2\">Tenosynovitis de Quervain<\/span><\/span> <\/span>auf sanfte, effektive und nat\u00fcrliche Weise, indem Muskelungleichgewichte, Narbengewebe, Triggerpunkte, Faszieneinschr\u00e4nkungen, Entz\u00fcndungen, Haltungen und K\u00f6rpermechaniken angegangen werden, die oft die Quelle der Schmerzen sind. ASTR verfolgt einen ganzheitlichen Ansatz, um die Ursachen von Schmerzen anzugehen, nicht nur die Symptome. Die ASTR-Behandlung kann zu Hause durchgef\u00fchrt werden<span class=\"Apple-converted-space\"> <span style=\"color: #696969;\"><span class=\"s2\">Tenosynovitis de Quervain.<\/span><\/span><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a408c96 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a408c96\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fed302d\" data-id=\"fed302d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8167468 uael-heading-align-center elementor-widget elementor-widget-uael-advanced-heading\" data-id=\"8167468\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"uael-advanced-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"uael-module-content uael-heading-wrapper\">\n\t\t\t\t\t\t\n\t\t\t<h1 class=\"uael-heading\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-heading-text elementor-inline-editing uael-size--default\" data-elementor-setting-key=\"heading_title\" data-elementor-inline-editing-toolbar=\"basic\">De Quervain&#039;s Sehnenscheidenentz\u00fcndung Heimbehandlung<\/span>\n\t\t\t\t\t\t\t<\/h1>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2b39e31 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2b39e31\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2ec5c64\" data-id=\"2ec5c64\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b544ed5 uael-aspect-ratio-16_9 uael-youtube-subscribe-no elementor-widget elementor-widget-uael-video\" data-id=\"b544ed5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"uael-video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-video__outer-wrap  uael-video-type-youtube uael-video-play-lightbox\" data-device=\"false\" data-vsticky=\"no\" data-hidedesktop=\"\" data-hidetablet=\"\" data-hidemobile=\"\" data-vsticky-viewport=\"0\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox=\"{&quot;type&quot;:&quot;video&quot;,&quot;videoType&quot;:&quot;youtube&quot;,&quot;url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/embed\\\/EWL3NHpDQQI?rel=0&amp;start&amp;end&amp;controls=1&amp;mute=0&amp;modestbranding=0&amp;&quot;,&quot;modalOptions&quot;:{&quot;id&quot;:&quot;elementor-lightbox-b544ed5&quot;,&quot;entranceAnimation&quot;:&quot;&quot;,&quot;entranceAnimation_tablet&quot;:&quot;&quot;,&quot;entranceAnimation_mobile&quot;:&quot;&quot;,&quot;videoAspectRatio&quot;:&quot;169&quot;}}\">\n\t\t\t\t\t\t<div class=\"uael-video-inner-wrap\">\n\t\t\t\t<div class=\"uael-video__play\" data-src=\"https:\/\/www.youtube.com\/embed\/EWL3NHpDQQI?rel=0&amp;start&amp;end&amp;controls=1&amp;mute=0&amp;modestbranding=0&amp;\">\n\t\t\t\t\t<img decoding=\"async\" class=\"uael-video__thumb\" src=\"https:\/\/i.ytimg.com\/vi\/EWL3NHpDQQI\/maxresdefault.jpg\" alt=\"\"><\/img>\n\t\t\t\t\t<div class=\"uael-video__play-icon uael-animation-\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-play-circle\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-40ded61\" data-id=\"40ded61\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bb5359a elementor-widget elementor-widget-heading\" data-id=\"bb5359a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/advancedsofttissuerelease.com\/de\/behandeln-ihre-schmerzen-zu-hause-2\/\">Behandeln Sie Ihre Schmerzen zu Hause<\/a><\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b044da7 elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"b044da7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-smile\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Schnelle Ergebnisse<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"auxicon auxicon-zap\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Die Behandlung dauert etwa 5 Minuten pro Tag<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"auxicon auxicon-thumbs-up\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Einfach zu verwendende medizinische Hilfsmittel<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Nat\u00fcrlicher ganzheitlicher Ansatz<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"auxicon auxicon-search-5\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Behandlung der Grundursache des Problems<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-user-md\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Erfunden von einem Arzt, der chronische Schmerzen hatte<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/advancedsofttissuerelease.com\/de\/was-ist-astr-2\/forschung-2\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"auxicon auxicon-book-open\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Gest\u00fctzt durch \u00fcber 45 Studien<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-82600a2 elementor-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"82600a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/advancedsofttissuerelease.com\/de\/behandeln-ihre-schmerzen-zu-hause-2\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Beginnen Sie Ihre Reise der Heilung heute<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f3b39b2 elementor-widget elementor-widget-heading\" data-id=\"f3b39b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/advancedsofttissuerelease.com\/de\/produkt\/behandle-deine-schmerzen-zu-hause-zahlungsplan-2\/\">Zahlungspl\u00e4ne verf\u00fcgbar<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-307c4aa elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"307c4aa\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0899132\" data-id=\"0899132\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1f792c6 elementor-widget elementor-widget-heading\" data-id=\"1f792c6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ASTR Au\u00dfergew\u00f6hnlich anders<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-734a7ed elementor-widget elementor-widget-text-editor\" data-id=\"734a7ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Von verschiedenen Websites gesammelte Bewertungen<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f467741 elementor-star-rating--align-center elementor--star-style-star_fontawesome elementor-widget elementor-widget-star-rating\" data-id=\"f467741\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"star-rating.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-star-rating__wrapper\">\n\t\t\t\t\t\t<div class=\"elementor-star-rating\" itemtype=\"http:\/\/schema.org\/Rating\" itemscope=\"\" itemprop=\"reviewRating\">\n\t\t\t\t<i class=\"elementor-star-full\" aria-hidden=\"true\">\ue934<\/i><i class=\"elementor-star-full\" aria-hidden=\"true\">\ue934<\/i><i class=\"elementor-star-full\" aria-hidden=\"true\">\ue934<\/i><i class=\"elementor-star-full\" aria-hidden=\"true\">\ue934<\/i><i class=\"elementor-star-full\" aria-hidden=\"true\">\ue934<\/i>\t\t\t\t<span itemprop=\"ratingValue\" class=\"elementor-screen-only\" data-no-translation=\"\" data-trp-gettext=\"\">\u8bc4\u5206\u4e3a 5\uff08\u5171 5\uff09<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5907be0 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"5907be0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/advancedsofttissuerelease.com\/de\/behandlungsvideos-2-2\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Videos zur Behandlung und Nachsorge ansehen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b37b7e elementor-testimonial--skin-default elementor-testimonial--layout-image_inline elementor-testimonial--align-center elementor-arrows-yes elementor-pagination-type-bullets elementor-widget elementor-widget-testimonial-carousel\" data-id=\"3b37b7e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_per_view&quot;:&quot;3&quot;,&quot;show_arrows&quot;:&quot;yes&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;speed&quot;:500,&quot;loop&quot;:&quot;yes&quot;,&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]}}\" data-widget_type=\"testimonial-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slides\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"Ich habe mich mit den sich verschlimmernden Auswirkungen von Morbus Bechterew (Wirbels\u00e4ulenarthritis, R\u00fcckenschmerzen) herumgeschlagen. Nachdem ich <b>seit \u00fcber 40 Jahren mit der Krankheit lebt<\/b>Ich war skeptisch, dass eine Linderung m\u00f6glich sein w\u00fcrde. Zu meinem Erstaunen erlebte ich\u00a0<b>sofortige Linderung nach einer Sitzung<\/b>. Ich wei\u00df Ihre Arbeit sehr zu sch\u00e4tzen.\"\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Wilhelm K.<\/span><span class=\"elementor-testimonial__title\">R\u00fcckenschmerzen<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"Nachdem ich <b>18 Monate traditionelle Physiotherapie nach zwei Knieoperationen<\/b> Ich war skeptisch, dass man noch mehr gegen meine Knieschmerzen und meine Steifheit tun k\u00f6nnte, als ich das ACL ersetzen lie\u00df.\u00a0<b>Nach nur einem Besuch<\/b>Ich war erstaunt \u00fcber die Ergebnisse, die Dr. Jacobs mit seiner Advanced Soft Tissue Release Technik erzielen konnte! .... Ich war sehr beeindruckt, wie mein Knie reagiert hat und sich gelockert hat, vor allem, weil meine urspr\u00fcngliche Operation schon zwei Jahre her ist.\u00a0<b>Ich war anfangs skeptisch und jetzt bin ich \u00fcberzeugt!<\/b>\"\u00a0\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Mychal T<\/span><span class=\"elementor-testimonial__title\">Knieschmerzen<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"F\u00fcr <b>ein Jahr<\/b>Ich konnte meine Hand nicht \u00f6ffnen. Mein Daumen lie\u00df sich ohne gro\u00dfe Schmerzen nur sehr eingeschr\u00e4nkt bewegen. Es war schwierig, etwas zu heben, selbst etwas Kleines, oder meine Hand auf eine bestimmte Weise zu bewegen, ohne Schmerzen zu haben. Letztes Jahr habe ich mir zwei Injektionen zur Schmerzbek\u00e4mpfung geben lassen. Und davor,<b> Ich habe etwa 5-6 Monate lang Chiropraktik gemacht, aber die Schmerzen kamen immer wieder zur\u00fcck.<\/b>. Seit heute habe ich <b>3 ASTR-Behandlungen<\/b>. Ich kann meine Hand vollst\u00e4ndig \u00f6ffnen und sp\u00fcre \u00fcberhaupt keinen Schmerz. <b>ASTR funktioniert! Zweifellos, es funktioniert!<\/b>\"\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Carol<\/span><span class=\"elementor-testimonial__title\">Schmerzen in der Hand<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"Zusammen mit dem <b>Ausschluss von Medikamenten<\/b>.\u00a0<b>Die ASTR-Technik hat die H\u00e4ufigkeit und Intensit\u00e4t meiner Migr\u00e4ne enorm reduziert.<\/b>\"\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Jessica Y.<\/span><span class=\"elementor-testimonial__title\">Migr\u00e4ne<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"Ich habe\u00a0<b>schnell erholt<\/b>\u00a0Dank Dr. Jacobs haben sich meine Schmerzen nicht nur deutlich verringert, sondern sind sogar ganz verschwunden. Die ASTR-Technik von Dr. Jacob wirkt schnell. Das Beste daran ist, dass sie\u00a0<b>schmerzfrei<\/b>. Ich w\u00fcrde seine Therapie auf jeden Fall jedem empfehlen, den ich mit chronischen Schmerzen kenne.\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Candace P<\/span><span class=\"elementor-testimonial__title\">Kieferschmerzen<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"Nach seiner Behandlung konnte ich alle meine normalen Aktivit\u00e4ten wieder aufnehmen und die\u00a0<b>Die Kopfschmerzen sind nicht zur\u00fcckgekehrt<\/b>.\"\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Jeremy R.<\/span><span class=\"elementor-testimonial__title\">Kopfschmerzen<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"Ich hatte eine Muskelzerrung in meinem Unterarm und meinem Bizeps. Ich konnte mich nur eingeschr\u00e4nkt bewegen, konnte nicht schlafen und meinen Arm nicht ausstrecken. Nach <b>3 Sitzungen<\/b>war ich <b>schmerzfrei<\/b>. Und nach der vierten Sitzung hatte ich wieder die volle Beweglichkeit, konnte schlafen und fange sogar wieder an, zu trainieren. <b>Ich bin sehr zufrieden mit der Therapie und den Ergebnissen!<\/b>\"\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Kathy<\/span><span class=\"elementor-testimonial__title\">Schmerzen im Ellenbogen<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"Ich hatte <b>Kopfschmerzen \u00fcber 50% der Zeit<\/b> in den letzten Monaten. Nach mehreren Behandlungen begannen meine Kopfschmerzen zu schwinden und <b>Ich bin seit ein paar Monaten kopfschmerzfrei.<\/b>. Es ist wunderbar, keine Schmerzen zu haben\".\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Liz S<\/span><span class=\"elementor-testimonial__title\">Kopfschmerzen<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"Ich bin jetzt seit \u00fcber 3 Jahren in der Physiotherapie t\u00e4tig. Vor 6 Monaten begann ich mit Dr. Jacobs zu arbeiten und ich muss sagen, dass <b>Ich habe noch nie eine so erfolgreiche Genesung von Patienten erlebt wie hier.<\/b>.  Dr. Joseph Jacobs wei\u00df definitiv, wie er mit seinen patentierten Werkzeugen und Methoden der physikalischen Therapie an die Wurzel des Leidens des Patienten kommt. <b>Anfangs war ich skeptisch, aber nachdem ich wiederholt die Genesung von Patienten miterlebt habe, glaube ich inzwischen an seine Praxis.<\/b>. Ich bin stolz darauf, den Patienten bei ihrer Genesung helfen zu k\u00f6nnen.\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Dee Ann Pope<\/span><span class=\"elementor-testimonial__title\">Fr\u00fchere Mitarbeiterin<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"Ich hatte fast jeden Tag nach der Arbeit starke Kopfschmerzen. Nach nur einem <b>erster Besuch<\/b> meine Kopfschmerzen waren weg und <b>sind nicht zur\u00fcckgekommen<\/b>\"\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Drew A<\/span><span class=\"elementor-testimonial__title\">Kopfschmerzen<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"In der Vergangenheit <b>Jahr<\/b>Ich bekam ein Taubheitsgef\u00fchl und einen Krampf im Fu\u00df. Das Taubheitsgef\u00fchl war furchtbar und ich wusste nicht, was ich tun sollte. Nach 7 ASTR-Behandlungen, <b>jetzt f\u00fchle ich \u00fcberhaupt keinen Schmerz mehr<\/b>. Es war alles sehr bequem.\"\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Richard<\/span><span class=\"elementor-testimonial__title\">Fu\u00dfschmerzen<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"Ich kam mit Kiefergelenksbeschwerden, eingeschr\u00e4nkter Beweglichkeit und Schmerzen im Nacken und in den Schultern (mit stechenden Schmerzen \u00fcber dem rechten Ohr) zu mir. Nach nur\u00a0<b>eine Behandlung<\/b>mein Nacken und meine Schultern wurden <b>sofortige Erleichterung!<\/b> Nach 3 Behandlungen war mein stechender Schmerz \u00fcber dem Ohr verschwunden. Ich bin zuversichtlich, dass ich mich mit \"Advanced Soft Tissue Release\" und meinem Flei\u00df beim Befolgen des angebotenen \u00dcbungsprogramms bald wieder wie neu f\u00fchlen werde.\"\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Margarete E.<\/span><span class=\"elementor-testimonial__title\">Kieferschmerzen<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"Vor der Behandlung hatte ich eine sehr eingeschr\u00e4nkte Bewegungsfreiheit, wenn ich meinen Hals von einer Seite zur anderen drehte oder mich nach vorne beugte. Nach einer Behandlung sp\u00fcrte ich eine Entspannung und konnte meinen Nacken mit weniger Stress beugen und drehen. Die Behandlung war <b>schmerzfrei<\/b>Sie ist nicht invasiv und besser als jede Massage, die ich je hatte!\"\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Cathy<\/span><span class=\"elementor-testimonial__title\">Nackenschmerzen<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"<b>Nach etwa einer Woche f\u00fchlte ich mich wieder normal.<\/b>. Mein Handgelenk ist nach zwei Wochen fast wieder voll beweglich und die Schmerzen sind deutlich zur\u00fcckgegangen. <b>Ich kann ASTR nur jedem empfehlen.<\/b>\"\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Alex B.<\/span><span class=\"elementor-testimonial__title\">R\u00fccken- und Handgelenksschmerzen<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"Vor drei Tagen hatte ich einen Nackenkrampf und konnte meinen Nacken nicht mehr bewegen. Mein Nacken war steif und meine Schulter war wirklich taub. Jetzt habe ich fast <b>keine Schmerzen<\/b>. Ich hatte <b>drei Behandlungen<\/b> und jetzt kann ich meinen Hals bewegen.\"\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Anthony<\/span><span class=\"elementor-testimonial__title\">Nackenschmerzen<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\" <b>Es war ein frustrierender Prozess mit 3 Monaten Physiotherapie, 2 Kortisonspritzen und 3 verschiedenen Orthesen mit minimaler Linderung.<\/b>....Vielen Dank, Dr. Jacobs, f\u00fcr die Erleichterung meiner <b>Schmerzen bei chronischer Plantarfasziitis<\/b>. Ich beschloss, das gesamte Programm zu verfolgen und in nur <b>3 Besuche<\/b> Sie kennen sich aus und sind sehr klug darin, die ASTR-Tools und die Behandlung zu erfinden. Ich hoffe, dass mehr \u00c4rzte von Ihnen lernen werden.\"\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Elsie J<\/span><span class=\"elementor-testimonial__title\">Plantar-Fasziitis<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"Ich habe in den letzten Jahren unter chronischen Nacken-, Schulter- und Knieschmerzen aufgrund von Fibromyalgie gelitten. <b>12 Jahre<\/b>.<b> Ich habe Massage, Physiotherapie, Chiropraktik und Medikamente ausprobiert, aber ich habe immer noch Schmerzen.<\/b>. Nachdem ich Dr. Jacobs Empfehlungen zu Ern\u00e4hrung, Verhaltens\u00e4nderung, Ergonomie und Nahrungserg\u00e4nzung befolgt hatte, war mein <b>Fibromyalgiesymptome wurden durch 90% verringert<\/b>.\"\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\"> Liam M<\/span><span class=\"elementor-testimonial__title\">Fibromyalgie, Schmerzen im Nacken, in den Schultern und in den Knien<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"Eine erstaunliche Technik hat mir geholfen, Narbengewebe in meinem Kiefer, Hals, Bauch und nach einer Brustimplantatoperation aufzul\u00f6sen. <b> Ich habe erstaunlicherweise keine Schmerzen mehr<\/b>\"\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Janice Lachs<\/span><span class=\"elementor-testimonial__title\">Kiefer-, Nacken- und Magenschmerzen<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"Ich war vor 3 Jahren bei Dr. Jacobs wegen <b>t\u00e4gliche Spannungskopfschmerzen<\/b>.  Ich war ungl\u00fccklich und nahm <b>Advil t\u00e4glich<\/b>.  Nach mehreren Behandlungen begann das Narbengewebe, von dem ich nicht einmal wusste, dass ich es an meinem Kopf und Hals hatte, endlich zu verschwinden.  Nach etwa 6 Wochen, <b>Ich hatte keine Kopfschmerzen mehr<\/b>.  Bis zum heutigen Tag wei\u00df ich es immer noch nicht!  Ich danke Ihnen!\"\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Melisse K<\/span><span class=\"elementor-testimonial__title\">Kopfschmerzen<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"Die <b>ASTR-Werkzeuge<\/b> wurden <b>\u00e4u\u00dferst n\u00fctzlich<\/b> gegen meine Kopfschmerzen oder Migr\u00e4ne, wenn ich sie kommen sp\u00fcre, sowie gegen Muskelverspannungen und andere Schmerzen.\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Stacy H<\/span><span class=\"elementor-testimonial__title\">Migr\u00e4ne<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"Die Physiotherapie ist nicht allt\u00e4glich, sie haben ein Verst\u00e4ndnis f\u00fcr den K\u00f6rper und eine Rehabilitationsmethode, die ich an anderen Orten noch nicht gesehen habe. Ich w\u00fcrde diesen Ort sehr empfehlen, da sie freundlich sind und zus\u00e4tzliche Schritte unternehmen, um<b> Ihnen helfen, k\u00f6rperlich wieder ganz zu werden<\/b>.\"\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Maher S<\/span><span class=\"elementor-testimonial__title\">R\u00fcckenschmerzen<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"Ich hatte eine Behandlung f\u00fcr mein Morton-Neurom, an dem ich seit 2 Jahren litt. Ich wurde medizinisch behandelt, aber es hat sich nichts ge\u00e4ndert. Der Arzt forderte mich auf, eine Operation durchzuf\u00fchren. Das wollte ich nicht. I <b>flog 24 Stunden<\/b> die Behandlung von Dr. Jacob zu bekommen: Sie hat sich wirklich gelohnt. Nach der <b>Erstbehandlung<\/b> war das Ergebnis offensichtlich: <b>keine Schmerzen mehr<\/b> und ich k\u00f6nnte wieder Schuhe tragen. <b>Einfach erstaunlich! 2 Wochen danach gibt es keine Anzeichen von Schmerzen mehr<\/b>. Mein Fu\u00df tut nicht mehr weh. Ich kann gehen und laufen. Ich kann eine ganze Nacht schlafen, ohne von den Schmerzen geweckt zu werden. Es ist gro\u00dfartig!\"\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Christine D.<\/span><span class=\"elementor-testimonial__title\">Morton-Neurom<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\" Meine R\u00fcckenschmerzen bestehen schon seit <b>7 Jahre<\/b> und nach <b>eine Behandlung<\/b> Es war, als w\u00e4re es ein neuer R\u00fccken. Ich kann ihn jetzt richtig bewegen und habe keine Schmerzen mehr.\nDie Behandlung ist wirklich gut, unglaublich gut!\"\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Christine D.<\/span><span class=\"elementor-testimonial__title\">R\u00fccken- und Nackenschmerzen<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"Ich hatte seit \u00fcber einem Jahr Schmerzen im unteren R\u00fcckenbereich. <b>5 Jahre<\/b>. Meine R\u00fcckenschmerzen wurden im letzten Jahr immer schlimmer. <b>Ich habe Massagen, Chiropraktik, Physiotherapie und Schmerzmittel ausprobiert, aber ich habe keine Linderung erfahren.<\/b>.....I n\u00e4ht ihn <b>zweimal und meine Schmerzen sind v\u00f6llig verschwunden<\/b>. Jetzt kann ich ohne R\u00fcckenschmerzen gehen, schlafen und Auto fahren. Ich glaube an Dr. Jacobs erfinderische Behandlung, die ASTR hei\u00dft. Ich kann die ASTR-Behandlung bei R\u00fccken- oder Muskelschmerzen nur empfehlen.\"\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Shea G<\/span><span class=\"elementor-testimonial__title\">R\u00fcckenschmerzen<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\" Nachdem ich Dr. Jacobs ..... aufgesucht habe, sind meine Knieschmerzen endlich weg. Sein Ansatz in der physikalischen Therapie ist sehr ganzheitlich. <b>Ich habe mehrere Monate damit verschwendet, zu traditionellen \u00c4rzten zu gehen.<\/b> der entschied, dass es an meiner Ern\u00e4hrung oder \"in meinem Kopf\" lag, ohne etwas zu erreichen, bevor er Dr. Jacobs fand.\"\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Norma F.<\/span><span class=\"elementor-testimonial__title\">Knieschmerzen<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"...Innerhalb von nur einem <b>wenige Minuten<\/b> Nach meiner ersten Behandlung gingen die Schmerzen und die Verspannungen in meinem Kiefer und Nacken von einer 8 auf eine 2 zur\u00fcck.\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Tiffany A<\/span><span class=\"elementor-testimonial__title\">Kieferschmerzen<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\" Mir geht es sehr gut nach einer <b>Paar-Sitzungen<\/b> mit Dr. Jacobs. Ich habe wenig zu <b>keine Schmerzen<\/b> jetzt. Was f\u00fcr eine Erleichterung!  Meine Erfahrung mit Dr. Jacobs war gro\u00dfartig. Vielen Dank!\"\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Lola G<\/span><span class=\"elementor-testimonial__title\">R\u00fcckenschmerzen<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\" Ich habe in der Vergangenheit unter Schmerzen im SI-Gelenk gelitten <b> 2 Jahre<\/b>. Es war so schlimm, dass ich mit dem Tanzen aufh\u00f6ren musste und mich sogar vor so etwas Einfachem wie einem Niesen sch\u00fctzen musste... Nach nur einem <b>wenige Besuche<\/b>Ich konnte bereits feststellen, dass die ASTR-Technik funktioniert!\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Alexandra Gonzalez<\/span><span class=\"elementor-testimonial__title\">R\u00fcckenschmerzen<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"Ich konnte nicht gehen, fahren oder sitzen. Mit dem <b>2 erster Besuch<\/b>Ich habe einen gro\u00dfen Unterschied gesp\u00fcrt, ich kann fahren und gehen, in der 3. Woche ist mein R\u00fccken fast normal.\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Nayibe Rahim<\/span><span class=\"elementor-testimonial__title\">Ischias<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"\u4ee5\u524d\u7684\" data-no-translation-aria-label=\"\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"\u4e0b\u4e00\u4e2a\" data-no-translation-aria-label=\"\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dd8d435 elementor-widget elementor-widget-heading\" data-id=\"dd8d435\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/advancedsofttissuerelease.com\/de\/produkt\/schmerzlindernde-creme\/\">Creme zur Schmerzlinderung<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d25340d elementor-widget elementor-widget-text-editor\" data-id=\"d25340d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><span style=\"color: #333333; font-size: medium;\"><span style=\"caret-color: #333333;\">Schneller heilen<\/span><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f49a355 elementor-align-center elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"f49a355\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/advancedsofttissuerelease.com\/de\/produkt\/schmerzlindernde-creme\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Jetzt einkaufen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-92f674f elementor-widget elementor-widget-image\" data-id=\"92f674f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/advancedsofttissuerelease.com\/de\/produkt\/schmerzlindernde-creme\/\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/advancedsofttissuerelease.com\/wp-content\/uploads\/2022\/02\/ASTR-pain-relief-cream-decrease-inflammation-cream-wound-care-cream-eczema-Psoriasis-dermatitis--scaled-e1645656839627-300x300.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-33765\" alt=\"ASTR-Schmerzlinderungscreme - Entz\u00fcndungshemmende Creme - Wundpflegecreme - Ekzem, Psoriasis, Dermatitis\" srcset=\"https:\/\/advancedsofttissuerelease.com\/wp-content\/uploads\/2022\/02\/ASTR-pain-relief-cream-decrease-inflammation-cream-wound-care-cream-eczema-Psoriasis-dermatitis--scaled-e1645656839627-300x300.jpg 300w, https:\/\/advancedsofttissuerelease.com\/wp-content\/uploads\/2022\/02\/ASTR-pain-relief-cream-decrease-inflammation-cream-wound-care-cream-eczema-Psoriasis-dermatitis--scaled-e1645656839627-100x100.jpg 100w, https:\/\/advancedsofttissuerelease.com\/wp-content\/uploads\/2022\/02\/ASTR-pain-relief-cream-decrease-inflammation-cream-wound-care-cream-eczema-Psoriasis-dermatitis--scaled-e1645656839627-520x520.jpg 520w, https:\/\/advancedsofttissuerelease.com\/wp-content\/uploads\/2022\/02\/ASTR-pain-relief-cream-decrease-inflammation-cream-wound-care-cream-eczema-Psoriasis-dermatitis--scaled-e1645656839627-1200x1200.jpg 1200w, https:\/\/advancedsofttissuerelease.com\/wp-content\/uploads\/2022\/02\/ASTR-pain-relief-cream-decrease-inflammation-cream-wound-care-cream-eczema-Psoriasis-dermatitis--scaled-e1645656839627-768x768.jpg 768w, https:\/\/advancedsofttissuerelease.com\/wp-content\/uploads\/2022\/02\/ASTR-pain-relief-cream-decrease-inflammation-cream-wound-care-cream-eczema-Psoriasis-dermatitis--scaled-e1645656839627-1000x1000.jpg 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-edd5561 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"edd5561\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ee577c3\" data-id=\"ee577c3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f8b5814 uael-aspect-ratio-16_9 uael-youtube-subscribe-no elementor-widget elementor-widget-uael-video\" data-id=\"f8b5814\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"uael-video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-video__outer-wrap  uael-video-type-youtube uael-video-play-lightbox\" data-device=\"false\" data-vsticky=\"no\" data-hidedesktop=\"\" data-hidetablet=\"\" data-hidemobile=\"\" data-vsticky-viewport=\"0\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox=\"{&quot;type&quot;:&quot;video&quot;,&quot;videoType&quot;:&quot;youtube&quot;,&quot;url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/embed\\\/07mLKtiiyBc?rel=0&amp;start&amp;end&amp;controls=1&amp;mute=0&amp;modestbranding=0&amp;&quot;,&quot;modalOptions&quot;:{&quot;id&quot;:&quot;elementor-lightbox-f8b5814&quot;,&quot;entranceAnimation&quot;:&quot;&quot;,&quot;entranceAnimation_tablet&quot;:&quot;&quot;,&quot;entranceAnimation_mobile&quot;:&quot;&quot;,&quot;videoAspectRatio&quot;:&quot;169&quot;}}\">\n\t\t\t\t\t\t<div class=\"uael-video-inner-wrap\">\n\t\t\t\t<div class=\"uael-video__play\" data-src=\"https:\/\/www.youtube.com\/embed\/07mLKtiiyBc?rel=0&amp;start&amp;end&amp;controls=1&amp;mute=0&amp;modestbranding=0&amp;\">\n\t\t\t\t\t<img decoding=\"async\" class=\"uael-video__thumb\" src=\"https:\/\/i.ytimg.com\/vi\/07mLKtiiyBc\/maxresdefault.jpg\" alt=\"\"><\/img>\n\t\t\t\t\t<div class=\"uael-video__play-icon uael-animation-\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-play-circle\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e52d95f\" data-id=\"e52d95f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-53747ab uael-aspect-ratio-16_9 uael-youtube-subscribe-no elementor-widget elementor-widget-uael-video\" data-id=\"53747ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"uael-video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-video__outer-wrap  uael-video-type-youtube uael-video-play-lightbox\" data-device=\"false\" data-vsticky=\"no\" data-hidedesktop=\"\" data-hidetablet=\"\" data-hidemobile=\"\" data-vsticky-viewport=\"0\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox=\"{&quot;type&quot;:&quot;video&quot;,&quot;videoType&quot;:&quot;youtube&quot;,&quot;url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/embed\\\/n1vv-ZY2G1w?rel=0&amp;start&amp;end&amp;controls=1&amp;mute=0&amp;modestbranding=0&amp;&quot;,&quot;modalOptions&quot;:{&quot;id&quot;:&quot;elementor-lightbox-53747ab&quot;,&quot;entranceAnimation&quot;:&quot;&quot;,&quot;entranceAnimation_tablet&quot;:&quot;&quot;,&quot;entranceAnimation_mobile&quot;:&quot;&quot;,&quot;videoAspectRatio&quot;:&quot;169&quot;}}\">\n\t\t\t\t\t\t<div class=\"uael-video-inner-wrap\">\n\t\t\t\t<div class=\"uael-video__play\" data-src=\"https:\/\/www.youtube.com\/embed\/n1vv-ZY2G1w?rel=0&amp;start&amp;end&amp;controls=1&amp;mute=0&amp;modestbranding=0&amp;\">\n\t\t\t\t\t<img decoding=\"async\" class=\"uael-video__thumb\" src=\"https:\/\/i.ytimg.com\/vi\/n1vv-ZY2G1w\/maxresdefault.jpg\" alt=\"\"><\/img>\n\t\t\t\t\t<div class=\"uael-video__play-icon uael-animation-\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-play-circle\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>De Quervain\u2019s\u00a0Tenosynovitis: Symptoms &amp;\u00a0Treatment\u00a0 What is De Quervain\u2019s tenosynovitis? De Quervain\u2019s tenosynovitis disease is painful condition caused by inflammation of tendons on the thumb side of the wrist.\u00a0 Grasping, making a fist, or working with the hands can agitate symptoms of De Quervain\u2019s disease.\u00a0 De Quervain\u2019s tenosynovitis disease affects women 8 out of 10 times [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":120,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_analytify_skip_tracking":false,"footnotes":""},"class_list":["post-232","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/advancedsofttissuerelease.com\/de\/wp-json\/wp\/v2\/pages\/232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/advancedsofttissuerelease.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/advancedsofttissuerelease.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/advancedsofttissuerelease.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/advancedsofttissuerelease.com\/de\/wp-json\/wp\/v2\/comments?post=232"}],"version-history":[{"count":0,"href":"https:\/\/advancedsofttissuerelease.com\/de\/wp-json\/wp\/v2\/pages\/232\/revisions"}],"wp:attachment":[{"href":"https:\/\/advancedsofttissuerelease.com\/de\/wp-json\/wp\/v2\/media?parent=232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}