{"id":178,"date":"2016-04-23T17:28:13","date_gmt":"2016-04-23T23:28:13","guid":{"rendered":"https:\/\/advancedsofttissuerelease.com\/low-back-pain\/"},"modified":"2022-02-20T22:37:40","modified_gmt":"2022-02-21T05:37:40","slug":"lumbalgia-estadisticas-sintomas-causas-tratamiento-2","status":"publish","type":"page","link":"https:\/\/advancedsofttissuerelease.com\/es\/low-back-pain-statistics-symptoms-causes-treatment\/","title":{"rendered":"Dolor lumbar: estad\u00edsticas, s\u00edntomas, causas y tratamiento"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"178\" class=\"elementor elementor-178\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-651fd609 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"651fd609\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-77dc268e\" data-id=\"77dc268e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3f4136ba elementor-widget elementor-widget-text-editor\" data-id=\"3f4136ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1 class=\"p1\"><strong><span style=\"font-family: verdana,geneva,sans-serif;\"><span style=\"color: #696969;\"><span class=\"s1\">Dolor lumbar: estad\u00edsticas, s\u00edntomas, causas y tratamiento<\/span><\/span><\/span><\/strong><\/h1><div><strong><span style=\"font-family: verdana,geneva,sans-serif;\"><span style=\"color: #696969;\"><span class=\"s1\">\u00a0<\/span><\/span><\/span><\/strong><\/div><h2 class=\"p1\"><strong><span style=\"font-family: verdana,geneva,sans-serif;\"><span style=\"color: #696969;\"><span class=\"s1\">Estad\u00edsticas de dolor lumbar<\/span><\/span><\/span><\/strong><\/h2><p class=\"p1\"><span style=\"font-family: verdana,geneva,sans-serif;\"><span style=\"color: #696969;\"><span class=\"s1\">El dolor lumbar es muy com\u00fan y alrededor del 80% de los adultos lo experimentar\u00e1n en alg\u00fan momento de su vida. El dolor de espalda generalmente se debe a una mec\u00e1nica corporal deficiente y puede ocurrir repentinamente debido a una lesi\u00f3n o con el tiempo.\u00a0<\/span><\/span><\/span><\/p><h2 class=\"p1\"><span style=\"font-family: verdana,geneva,sans-serif;\"><span style=\"color: #696969;\"><span class=\"s1\">Causas del dolor lumbar<\/span><\/span><\/span><\/h2><p class=\"p1\"><span style=\"font-family: verdana,geneva,sans-serif;\"><span style=\"color: #696969;\"><span class=\"s1\">Las causas del dolor lumbar pueden incluir:\u00a0<\/span><\/span><\/span><\/p><ol style=\"margin-left: 120px;\"><li class=\"li1\"><span style=\"font-family: verdana,geneva,sans-serif;\"><span style=\"color: #696969;\"><span class=\"s1\">Esguinces\/Distensiones<\/span><\/span><\/span><\/li><li class=\"li1\"><span style=\"font-family: verdana,geneva,sans-serif;\"><span style=\"color: #696969;\"><span class=\"s1\">Degeneraci\u00f3n del disco<\/span><\/span><\/span><\/li><li class=\"li1\"><span style=\"font-family: verdana,geneva,sans-serif;\"><span style=\"color: #696969;\"><span class=\"s1\">Discos herniados o rotos<\/span><\/span><\/span><\/li><li class=\"li1\"><span style=\"font-family: verdana,geneva,sans-serif;\"><span style=\"color: #696969;\"><span class=\"s1\">Ci\u00e1tica<\/span><\/span><\/span><\/li><li class=\"li1\"><span style=\"font-family: verdana,geneva,sans-serif;\"><span style=\"color: #696969;\"><span class=\"s1\">radiculopat\u00eda\u00a0<\/span><\/span><\/span><\/li><li class=\"li1\"><span style=\"font-family: verdana,geneva,sans-serif;\"><span style=\"color: #696969;\"><span class=\"s1\">Estenosis espinal<\/span><\/span><\/span><\/li><li class=\"li1\"><span style=\"font-family: verdana,geneva,sans-serif;\"><span style=\"color: #696969;\"><span class=\"s1\">Irregularidades esquel\u00e9ticas<\/span><\/span><\/span><\/li><\/ol><h2 class=\"p2\"><strong><span style=\"font-size: 28px;\"><span style=\"font-family: verdana,geneva,sans-serif;\"><span style=\"color: #696969; line-height: 1.1;\">S\u00edntomas del dolor lumbar<\/span><\/span><\/span><\/strong><\/h2><p><span style=\"color: #696969;\"><span style=\"font-family: verdana,geneva,sans-serif;\">Los s\u00edntomas del dolor lumbar incluyen:<\/span><\/span><\/p><ol style=\"margin-left: 120px;\"><li class=\"li1\"><span style=\"font-family: verdana,geneva,sans-serif;\"><span style=\"color: #696969;\"><span class=\"s1\">Dolor sordo y doloroso<\/span><\/span><\/span><\/li><li class=\"li1\"><span style=\"font-family: verdana,geneva,sans-serif;\"><span style=\"color: #696969;\"><span class=\"s1\">Espasmos musculares<\/span><\/span><\/span><\/li><li class=\"li1\"><span style=\"font-family: verdana,geneva,sans-serif;\"><span style=\"color: #696969;\"><span class=\"s1\">Dolor local al tacto<\/span><\/span><\/span><\/li><li class=\"li1\"><span style=\"font-family: verdana,geneva,sans-serif;\"><span style=\"color: #696969;\"><span class=\"s1\">Dificultad para moverse<\/span><\/span><\/span><\/li><li class=\"li1\"><span style=\"font-family: verdana,geneva,sans-serif;\"><span style=\"color: #696969;\"><span class=\"s1\">Dolor que puede moverse hacia la ingle, las nalgas o los muslos.<\/span><\/span><\/span><\/li><\/ol><h2 class=\"p1\"><strong><span style=\"color: #696969;\">Tratamiento del dolor lumbar<\/span><\/strong><\/h2><p class=\"p1\"><span style=\"color: #696969; font-family: verdana, geneva, sans-serif; font-size: 16px; line-height: 25.6px;\">ASTR trata el dolor lumbar de una manera suave, eficaz y natural al abordar los desequilibrios musculares, el tejido cicatricial, los puntos gatillo, la inflamaci\u00f3n, la postura, la mec\u00e1nica corporal y la restricci\u00f3n de la fascia, que a menudo son la fuente del dolor. ASTR adopta un enfoque hol\u00edstico para abordar las causas fundamentales del dolor, no solo los s\u00edntomas. El tratamiento ASTR se puede hacer en casa para el dolor lumbar<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1a8baf8 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1a8baf8\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-513cda1\" data-id=\"513cda1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f610777 uael-heading-align-center elementor-widget elementor-widget-uael-advanced-heading\" data-id=\"f610777\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"uael-advanced-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"uael-module-content uael-heading-wrapper\">\n\t\t\t\t\t\t\n\t\t\t<h1 class=\"uael-heading\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-heading-text elementor-inline-editing uael-size--default\" data-elementor-setting-key=\"heading_title\" data-elementor-inline-editing-toolbar=\"basic\">Tratamiento en el hogar para el dolor lumbar<\/span>\n\t\t\t\t\t\t\t<\/h1>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0eefade elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0eefade\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-dc83553\" data-id=\"dc83553\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7f7bc1c uael-aspect-ratio-16_9 uael-youtube-subscribe-no elementor-widget elementor-widget-uael-video\" data-id=\"7f7bc1c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"uael-video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-video__outer-wrap  uael-video-type-youtube uael-video-play-lightbox\" data-device=\"false\" data-vsticky=\"no\" data-hidedesktop=\"\" data-hidetablet=\"\" data-hidemobile=\"\" data-vsticky-viewport=\"0\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox=\"{&quot;type&quot;:&quot;video&quot;,&quot;videoType&quot;:&quot;youtube&quot;,&quot;url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/embed\\\/EWL3NHpDQQI?rel=0&amp;start&amp;end&amp;controls=1&amp;mute=0&amp;modestbranding=0&amp;&quot;,&quot;modalOptions&quot;:{&quot;id&quot;:&quot;elementor-lightbox-7f7bc1c&quot;,&quot;entranceAnimation&quot;:&quot;&quot;,&quot;entranceAnimation_tablet&quot;:&quot;&quot;,&quot;entranceAnimation_mobile&quot;:&quot;&quot;,&quot;videoAspectRatio&quot;:&quot;169&quot;}}\">\n\t\t\t\t\t\t<div class=\"uael-video-inner-wrap\">\n\t\t\t\t<div class=\"uael-video__play\" data-src=\"https:\/\/www.youtube.com\/embed\/EWL3NHpDQQI?rel=0&amp;start&amp;end&amp;controls=1&amp;mute=0&amp;modestbranding=0&amp;\">\n\t\t\t\t\t<img decoding=\"async\" class=\"uael-video__thumb\" src=\"https:\/\/i.ytimg.com\/vi\/EWL3NHpDQQI\/maxresdefault.jpg\" alt=\"\"><\/img>\n\t\t\t\t\t<div class=\"uael-video__play-icon uael-animation-\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-play-circle\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0372f45\" data-id=\"0372f45\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aefcb7d elementor-widget elementor-widget-heading\" data-id=\"aefcb7d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/advancedsofttissuerelease.com\/es\/tratar-su-dolor-en-casa-2\/\">Tratar el dolor en casa<\/a><\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8f7337f elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"8f7337f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-smile\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Resultados r\u00e1pidos<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"auxicon auxicon-zap\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">El tratamiento dura unos 5 minutos al d\u00eda<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"auxicon auxicon-thumbs-up\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Herramientas m\u00e9dicas f\u00e1ciles de usar<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Enfoque hol\u00edstico natural<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"auxicon auxicon-search-5\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Tratar la ra\u00edz del problema<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-user-md\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Inventado por un m\u00e9dico que ten\u00eda dolor cr\u00f3nico<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/advancedsofttissuerelease.com\/es\/que-es-astr-2\/investigar-2\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"auxicon auxicon-book-open\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Apoyado por m\u00e1s de 45 estudios<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d58a8c8 elementor-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"d58a8c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/advancedsofttissuerelease.com\/es\/tratar-su-dolor-en-casa-2\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Comience hoy su viaje de curaci\u00f3n<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5b806e2 elementor-widget elementor-widget-heading\" data-id=\"5b806e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/advancedsofttissuerelease.com\/es\/producto\/tratamiento-su-dolor-en-casa-plan-de-pago-2\/\">Planes de pago disponibles<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-71ac3d9 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"71ac3d9\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-af1d058\" data-id=\"af1d058\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-13420e4 elementor-widget elementor-widget-heading\" data-id=\"13420e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ASTR excepcionalmente diferente<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-be0abd1 elementor-widget elementor-widget-text-editor\" data-id=\"be0abd1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Rese\u00f1as recopiladas de varios sitios web<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b1579ca elementor-star-rating--align-center elementor--star-style-star_fontawesome elementor-widget elementor-widget-star-rating\" data-id=\"b1579ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"star-rating.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-star-rating__wrapper\">\n\t\t\t\t\t\t<div class=\"elementor-star-rating\" itemtype=\"http:\/\/schema.org\/Rating\" itemscope=\"\" itemprop=\"reviewRating\">\n\t\t\t\t<i class=\"elementor-star-full\" aria-hidden=\"true\">\ue934<\/i><i class=\"elementor-star-full\" aria-hidden=\"true\">\ue934<\/i><i class=\"elementor-star-full\" aria-hidden=\"true\">\ue934<\/i><i class=\"elementor-star-full\" aria-hidden=\"true\">\ue934<\/i><i class=\"elementor-star-full\" aria-hidden=\"true\">\ue934<\/i>\t\t\t\t<span itemprop=\"ratingValue\" class=\"elementor-screen-only\">Rated 5 out of 5<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b0f93b elementor-align-center elementor-widget elementor-widget-button\" data-id=\"7b0f93b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/advancedsofttissuerelease.com\/es\/tratamientos-videos-2-2\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Ver v\u00eddeos de tratamiento y seguimiento<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-28c1c9d elementor-testimonial--skin-default elementor-testimonial--layout-image_inline elementor-testimonial--align-center elementor-arrows-yes elementor-pagination-type-bullets elementor-widget elementor-widget-testimonial-carousel\" data-id=\"28c1c9d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_per_view&quot;:&quot;3&quot;,&quot;show_arrows&quot;:&quot;yes&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;speed&quot;:500,&quot;loop&quot;:&quot;yes&quot;,&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]}}\" data-widget_type=\"testimonial-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slides\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"He tenido problemas con el empeoramiento de los efectos de la espondilitis anquilosante (artritis de la columna vertebral, dolor de espalda). Despu\u00e9s de tener <b>vivi\u00f3 con la enfermedad durante m\u00e1s de 40 a\u00f1os<\/b>Me sent\u00eda esc\u00e9ptico de que fuera posible un alivio. Para mi asombro, experiment\u00e9\u00a0<b>alivio inmediato despu\u00e9s de una sesi\u00f3n<\/b>. Aprecio mucho el trabajo que hacen\".\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">William K<\/span><span class=\"elementor-testimonial__title\">Dolor de espalda<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"Despu\u00e9s de haber <b>18 meses de fisioterapia tradicional tras dos operaciones de rodilla<\/b> para reemplazar mi LCA, era esc\u00e9ptico de que se pudiera hacer algo m\u00e1s para ayudar a mi dolor y rigidez de rodilla.\u00a0<b>Despu\u00e9s de una sola visita<\/b>Me sorprendieron los resultados que el doctor Jacobs fue capaz de producir con su t\u00e9cnica de liberaci\u00f3n avanzada de tejidos blandos. .... Qued\u00e9 muy impresionado con la forma en que mi rodilla respondi\u00f3 y se afloj\u00f3, especialmente porque han pasado dos a\u00f1os desde mi cirug\u00eda original.\u00a0<b>Fui un esc\u00e9ptico y ahora soy un creyente.<\/b>\"\u00a0\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Mychal T<\/span><span class=\"elementor-testimonial__title\">Dolor de rodilla<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"Para <b>un a\u00f1o<\/b>No pod\u00eda abrir la mano. Mi pulgar ten\u00eda un movimiento muy limitado sin mucho dolor. Era dif\u00edcil levantar cualquier cosa, aunque fuera peque\u00f1a, o mover la mano de cierta manera sin que me doliera. El a\u00f1o pasado me pusieron dos inyecciones en la zona para controlar el dolor. Y antes de eso,<b> Hice unos 5-6 meses de quiropr\u00e1ctica, pero el dolor siempre volv\u00eda a aparecer<\/b>. A partir de hoy, he tenido <b>3 tratamientos ASTR<\/b>. Puedo abrir la mano completamente y no siento ning\u00fan dolor. <b>\u00a1ASTR funciona! Sin duda, \u00a1funciona!<\/b>\"\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Carol<\/span><span class=\"elementor-testimonial__title\">Dolor de manos<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"Junto con el <b>eliminaci\u00f3n de la medicaci\u00f3n<\/b>.\u00a0<b>La t\u00e9cnica ASTR redujo enormemente la frecuencia e intensidad de mis migra\u00f1as<\/b>\"\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Jessica Y<\/span><span class=\"elementor-testimonial__title\">Migra\u00f1as<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"Tengo\u00a0<b>se recuper\u00f3 r\u00e1pidamente<\/b>\u00a0Gracias al doctor Jacobs, mi dolor no s\u00f3lo ha disminuido considerablemente, sino que se ha eliminado por completo. La t\u00e9cnica ASTR del doctor Jacobs funciona r\u00e1pidamente. Lo que m\u00e1s me gusta es que es\u00a0<b>sin dolor<\/b>. Definitivamente recomendar\u00eda su terapia a cualquier persona que conozca con dolor cr\u00f3nico\".\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Candace P<\/span><span class=\"elementor-testimonial__title\">Dolor de mand\u00edbula<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"Pude reanudar todas mis actividades normales tras su tratamiento y el\u00a0<b>el dolor de cabeza no volvi\u00f3<\/b>.\"\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Jeremy R<\/span><span class=\"elementor-testimonial__title\">Dolor de cabeza<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"Ten\u00eda una distensi\u00f3n muscular en el antebrazo y el b\u00edceps. Ten\u00eda una amplitud de movimiento limitada, no pod\u00eda dormir y no pod\u00eda extender el brazo. Despu\u00e9s de <b>3 sesiones<\/b>, yo era <b>sin dolor<\/b>. Y despu\u00e9s de mi cuarta sesi\u00f3n ten\u00eda un rango completo de movimiento de nuevo, era capaz de dormir, y de hecho voy a volver y empezar a hacer ejercicio. <b>Estoy muy contento con la terapia y los resultados.<\/b>\"\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Kathy<\/span><span class=\"elementor-testimonial__title\">Dolor de codo<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"Estaba teniendo <b>dolores de cabeza sobre 50% del tiempo<\/b> desde hace varios meses. Despu\u00e9s de varios tratamientos mis dolores de cabeza empezaron a disminuir y <b>Llevo un par de meses sin dolores de cabeza<\/b>. Es maravilloso no tener dolor\".\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Liz S<\/span><span class=\"elementor-testimonial__title\">Dolor de cabeza<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"He estado en la industria de la terapia f\u00edsica por m\u00e1s de 3 a\u00f1os. Hace 6 meses, empec\u00e9 a trabajar con el Dr. Jacobs y tengo que decir que <b>Nunca he sido testigo de una tasa de recuperaci\u00f3n de pacientes tan exitosa como la de aqu\u00ed<\/b>.  El Dr. Joseph Jacobs definitivamente sabe c\u00f3mo llegar a la ra\u00edz de la dolencia de los pacientes por sus herramientas y m\u00e9todos patentados de terapia f\u00edsica. <b>Al principio era esc\u00e9ptico, pero despu\u00e9s de presenciar repetidamente la recuperaci\u00f3n de los pacientes, he llegado a creer en su pr\u00e1ctica<\/b>. Estoy orgulloso de formar parte de la ayuda a los pacientes en su recuperaci\u00f3n\".\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Dee Ann Pope<\/span><span class=\"elementor-testimonial__title\">Anterior Compa\u00f1ero de trabajo<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"Ten\u00eda fuertes dolores de cabeza casi todos los d\u00edas despu\u00e9s del trabajo. Despu\u00e9s de la <b>primera visita<\/b> mis dolores de cabeza hab\u00edan desaparecido y <b>no han vuelto<\/b>\"\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Drew A<\/span><span class=\"elementor-testimonial__title\">Dolor de cabeza<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"Para el pasado <b>a\u00f1o<\/b>Me estaba entumeciendo y apretando el pie. El entumecimiento era horrible y no sab\u00eda qu\u00e9 hacer. Despu\u00e9s de 7 tratamientos de ASTR, <b>ahora no siento ning\u00fan dolor<\/b>. Todo ha sido muy c\u00f3modo\".\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Richard<\/span><span class=\"elementor-testimonial__title\">Dolor de pies<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"Entr\u00e9 con una ATM, con una amplitud de movimiento limitada y con dolor en el cuello y los hombros (con un dolor punzante por encima de la oreja derecha). Despu\u00e9s de s\u00f3lo\u00a0<b>un tratamiento<\/b>Mi cuello y mis hombros se han puesto... <b>\u00a1alivio inmediato!<\/b> Despu\u00e9s de 3 tratamientos, mi dolor punzante por encima de la oreja hab\u00eda desaparecido. Estoy seguro de que con \"Advanced Soft Tissue Release\", y mi diligencia en seguir el programa de ejercicios proporcionado, pronto me sentir\u00e9 como nuevo de nuevo.\"\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Margarete E<\/span><span class=\"elementor-testimonial__title\">Dolor de mand\u00edbula<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"Antes del tratamiento, ten\u00eda una amplitud de movimiento muy limitada al girar el cuello de lado a lado o al inclinarse hacia delante. Despu\u00e9s de un tratamiento, sent\u00ed una liberaci\u00f3n y pude doblar y girar el cuello con menos tensi\u00f3n. El tratamiento fue <b>sin dolor<\/b>No es invasivo y es mejor que cualquier otro masaje que haya recibido\".\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Cathy<\/span><span class=\"elementor-testimonial__title\">Dolor de cuello<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"<b>Me sent\u00ed de vuelta a la normalidad despu\u00e9s de una semana<\/b>. Mi mu\u00f1eca ha recuperado casi todo su rango de movimiento despu\u00e9s de dos semanas y el dolor se ha reducido sustancialmente. <b>Recomendar\u00eda encarecidamente ASTR a cualquiera.<\/b>\"\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Alex B<\/span><span class=\"elementor-testimonial__title\">Dolor de espalda y de mu\u00f1eca<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"Tuve un espasmo cervical hace tres d\u00edas y no pod\u00eda mover el cuello. Ten\u00eda el cuello r\u00edgido y el hombro muy entumecido. Ahora tengo casi <b>sin dolor<\/b>. Yo ten\u00eda <b>tres tratamientos<\/b> y ahora puedo mover el cuello\".\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Anthony<\/span><span class=\"elementor-testimonial__title\">Dolor de cuello<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\" <b>Fue un proceso frustrante recibir 3 meses de terapia f\u00edsica, 2 inyecciones de cortisona y 3 ortesis diferentes con un alivio m\u00ednimo<\/b>....Muchas gracias Dr. Jacobs por aliviar mi <b>dolor cr\u00f3nico de fascitis plantar<\/b>. Decid\u00ed seguir todo el programa y en s\u00f3lo <b>3 visitas<\/b> He podido hacer 3 millas de caminata sin dolor.Usted sabe lo que hace y es muy inteligente al inventar las herramientas y el tratamiento de ASTR. Espero que m\u00e1s m\u00e9dicos aprendan de usted\".\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Elsie J<\/span><span class=\"elementor-testimonial__title\">Fascitis plantar<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"He estado sufriendo de dolor cr\u00f3nico de cuello, hombros y rodillas debido a la fibromialgia durante los \u00faltimos <b>12 a\u00f1os<\/b>.<b> Prob\u00e9 con masajes, fisioterapia, quiropr\u00e1ctica y medicaci\u00f3n, pero sigo experimentando dolor<\/b>. Despu\u00e9s de seguir el plan de dieta del Dr. Jacobs, la modificaci\u00f3n del comportamiento, la ergonom\u00eda y las recomendaciones de suplementos mi <b>Los s\u00edntomas de la fibromialgia han disminuido con el 90%<\/b>.\"\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\"> Liam M<\/span><span class=\"elementor-testimonial__title\">Fibromialgia, dolor de cuello, hombros y rodillas<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"Una t\u00e9cnica incre\u00edble que me ayud\u00f3 a romper el tejido cicatrizal en la mand\u00edbula, el cuello, el est\u00f3mago y despu\u00e9s de la cirug\u00eda de implantes mamarios. <b> Estoy sorprendentemente fuera del dolor<\/b>\"\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Janice Salmon<\/span><span class=\"elementor-testimonial__title\">Dolor de mand\u00edbula, cuello y est\u00f3mago<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"Vi al Dr. Jacobs hace 3 a\u00f1os para <b>cefaleas tensionales diarias<\/b>.  Me sent\u00eda miserable y tomaba <b>Advil todos los d\u00edas<\/b>.  Despu\u00e9s de varios tratamientos, el tejido cicatrizal que ni siquiera sab\u00eda que ten\u00eda en la cabeza y el cuello finalmente comenz\u00f3 a desaparecer.  Despu\u00e9s de unas 6 semanas, <b>Ya no ten\u00eda dolores de cabeza<\/b>.  \u00a1A d\u00eda de hoy sigo sin hacerlo!  Gracias\".\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Melissa K<\/span><span class=\"elementor-testimonial__title\">Dolor de cabeza<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"El <b>Herramientas ASTR<\/b> han sido <b>extremadamente \u00fatil<\/b> para evitar mis dolores de cabeza o migra\u00f1as cuando los siento venir, as\u00ed como los m\u00fasculos tensos y otros dolores\"\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Stacy H<\/span><span class=\"elementor-testimonial__title\">Migra\u00f1a<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"No es la fisioterapia de todos los d\u00edas, tienen una comprensi\u00f3n de su cuerpo y el m\u00e9todo de rehabilitaci\u00f3n que no he visto en otros lugares. Yo recomendar\u00eda este lugar, ya que son amables y toman medidas adicionales para<b> ayudarle a recuperarse f\u00edsicamente<\/b>.\"\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Maher S<\/span><span class=\"elementor-testimonial__title\">Dolor de espalda<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"Me somet\u00ed a un tratamiento para mi neuroma de Morton por el que llevaba 2 a\u00f1os sufriendo. Me somet\u00ed a un tratamiento m\u00e9dico pero nada cambi\u00f3. El m\u00e9dico me pidi\u00f3 que me operara. No quise hacerlo. I <b>vol\u00f3 24 horas<\/b> tener el tratamiento del Dr. Jacob: realmente vali\u00f3 la pena. Despu\u00e9s de la <b>primer tratamiento<\/b> el resultado era evidente: <b>ya no hay dolor<\/b> y podr\u00eda volver a usar zapatos. <b>Simplemente asombroso. 2 semanas despu\u00e9s, no hay m\u00e1s se\u00f1ales de dolor<\/b>. Ya no me duele el pie. Puedo caminar y correr. Puedo dormir una noche entera sin que me despierte el dolor. Es genial\".\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Christine D<\/span><span class=\"elementor-testimonial__title\">Neuroma de Morton<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\" Mi dolor de espalda hab\u00eda estado presente durante <b>7 a\u00f1os<\/b> y despu\u00e9s <b>un tratamiento<\/b> fue como si fuera una espalda nueva. Ahora puedo moverla correctamente y ya no hay dolor.\nEl tratamiento es realmente bueno, \u00a1incre\u00edble!\"\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Christine D<\/span><span class=\"elementor-testimonial__title\">Dolor de espalda y cuello<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"Llevaba m\u00e1s de un a\u00f1o sufriendo dolores lumbares <b>5 a\u00f1os<\/b>. Mi dolor de espalda estaba empeorando en el \u00faltimo a\u00f1o as\u00ed que <b>Prob\u00e9 la terapia de masaje, el cuidado quiropr\u00e1ctico, la terapia f\u00edsica y la medicaci\u00f3n para el dolor, pero no experiment\u00e9 alivio<\/b>.....I coserlo <b>dos veces y mi dolor ha desaparecido totalmente<\/b>. Ahora puedo caminar, dormir y conducir sin dolor de espalda. Soy un creyente del tratamiento inventivo del Dr. Jacobs llamado ASTR. Recomiendo encarecidamente el tratamiento ASTR para el dolor de espalda o muscular\".\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Shea G<\/span><span class=\"elementor-testimonial__title\">Dolor de espalda<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\" Finalmente consegu\u00ed aliviar mi dolor de rodilla despu\u00e9s de ir a ver al Dr. Jacobs ..... Su enfoque de la terapia f\u00edsica es muy hol\u00edstico. <b>Perd\u00ed varios meses yendo a m\u00e9dicos tradicionales<\/b> que decidi\u00f3 que era mi dieta o \"en mi cabeza\" sin llegar a nada antes de encontrar al Dr. Jacobs\".\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Norma F<\/span><span class=\"elementor-testimonial__title\">Dolor de rodilla<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"...Dentro de s\u00f3lo un <b>algunos minutos<\/b> de mi primer tratamiento, los niveles de dolor y tensi\u00f3n en la mand\u00edbula y el cuello pasaron de un 8 a un 2\"\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Tiffany A<\/span><span class=\"elementor-testimonial__title\">Dolor de mand\u00edbula<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\" Me va muy bien despu\u00e9s de un <b>sesiones en pareja<\/b> con el Dr. Jacobs. Tengo poco que <b>sin dolor<\/b> ahora. \u00a1Qu\u00e9 alivio!  Mi experiencia con el Dr. Jacobs ha sido genial. Gracias\".\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Lola G<\/span><span class=\"elementor-testimonial__title\">Dolor de espalda<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\" He sufrido de dolor en la articulaci\u00f3n SI durante el pasado <b> 2 a\u00f1os<\/b>. Era tan grave que tuve que dejar de bailar e incluso tuve que prepararme para algo tan simple como un estornudo... Despu\u00e9s de s\u00f3lo un <b>pocas visitas<\/b>Ya pod\u00eda decir que la t\u00e9cnica ASTR estaba funcionando.\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Alexandra Gonz\u00e1lez<\/span><span class=\"elementor-testimonial__title\">Dolor de espalda<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"No pod\u00eda caminar, conducir ni sentarme. Con el <b>2 primera visita<\/b>He notado una gran diferencia, puedo conducir y caminar, en la tercera semana mi espalda es casi normal\".\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Nayibe Rahim<\/span><span class=\"elementor-testimonial__title\">Ci\u00e1tica<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Anterior\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"pr\u00f3ximo\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f43a852 elementor-widget elementor-widget-heading\" data-id=\"f43a852\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/advancedsofttissuerelease.com\/es\/producto\/crema-analgesica-2\/\">Crema analg\u00e9sica<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7238ada elementor-widget elementor-widget-text-editor\" data-id=\"7238ada\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><span style=\"color: #333333; font-size: medium;\"><span style=\"caret-color: #333333;\">Sanar m\u00e1s r\u00e1pido<\/span><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fbe8830 elementor-align-center elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"fbe8830\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/advancedsofttissuerelease.com\/es\/producto\/crema-analgesica-2\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Comprar ahora<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e816a1 elementor-widget elementor-widget-image\" data-id=\"2e816a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/advancedsofttissuerelease.com\/es\/producto\/crema-analgesica-2\/\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/advancedsofttissuerelease.com\/wp-content\/uploads\/2022\/02\/ASTR-pain-relief-cream-decrease-inflammation-cream-wound-care-cream-eczema-Psoriasis-dermatitis--scaled-e1645656839627-300x300.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-33765\" alt=\"Crema para aliviar el dolor ASTR, crema para disminuir la inflamaci\u00f3n, crema para el cuidado de heridas, eccema, psoriasis, dermatitis\" srcset=\"https:\/\/advancedsofttissuerelease.com\/wp-content\/uploads\/2022\/02\/ASTR-pain-relief-cream-decrease-inflammation-cream-wound-care-cream-eczema-Psoriasis-dermatitis--scaled-e1645656839627-300x300.jpg 300w, https:\/\/advancedsofttissuerelease.com\/wp-content\/uploads\/2022\/02\/ASTR-pain-relief-cream-decrease-inflammation-cream-wound-care-cream-eczema-Psoriasis-dermatitis--scaled-e1645656839627-100x100.jpg 100w, https:\/\/advancedsofttissuerelease.com\/wp-content\/uploads\/2022\/02\/ASTR-pain-relief-cream-decrease-inflammation-cream-wound-care-cream-eczema-Psoriasis-dermatitis--scaled-e1645656839627-520x520.jpg 520w, https:\/\/advancedsofttissuerelease.com\/wp-content\/uploads\/2022\/02\/ASTR-pain-relief-cream-decrease-inflammation-cream-wound-care-cream-eczema-Psoriasis-dermatitis--scaled-e1645656839627-1200x1200.jpg 1200w, https:\/\/advancedsofttissuerelease.com\/wp-content\/uploads\/2022\/02\/ASTR-pain-relief-cream-decrease-inflammation-cream-wound-care-cream-eczema-Psoriasis-dermatitis--scaled-e1645656839627-768x768.jpg 768w, https:\/\/advancedsofttissuerelease.com\/wp-content\/uploads\/2022\/02\/ASTR-pain-relief-cream-decrease-inflammation-cream-wound-care-cream-eczema-Psoriasis-dermatitis--scaled-e1645656839627-1000x1000.jpg 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-14445c5 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"14445c5\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0564c70\" data-id=\"0564c70\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0a9cfb3 uael-aspect-ratio-16_9 uael-youtube-subscribe-no elementor-widget elementor-widget-uael-video\" data-id=\"0a9cfb3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"uael-video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-video__outer-wrap  uael-video-type-youtube uael-video-play-lightbox\" data-device=\"false\" data-vsticky=\"no\" data-hidedesktop=\"\" data-hidetablet=\"\" data-hidemobile=\"\" data-vsticky-viewport=\"0\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox=\"{&quot;type&quot;:&quot;video&quot;,&quot;videoType&quot;:&quot;youtube&quot;,&quot;url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/embed\\\/07mLKtiiyBc?rel=0&amp;start&amp;end&amp;controls=1&amp;mute=0&amp;modestbranding=0&amp;&quot;,&quot;modalOptions&quot;:{&quot;id&quot;:&quot;elementor-lightbox-0a9cfb3&quot;,&quot;entranceAnimation&quot;:&quot;&quot;,&quot;entranceAnimation_tablet&quot;:&quot;&quot;,&quot;entranceAnimation_mobile&quot;:&quot;&quot;,&quot;videoAspectRatio&quot;:&quot;169&quot;}}\">\n\t\t\t\t\t\t<div class=\"uael-video-inner-wrap\">\n\t\t\t\t<div class=\"uael-video__play\" data-src=\"https:\/\/www.youtube.com\/embed\/07mLKtiiyBc?rel=0&amp;start&amp;end&amp;controls=1&amp;mute=0&amp;modestbranding=0&amp;\">\n\t\t\t\t\t<img decoding=\"async\" class=\"uael-video__thumb\" src=\"https:\/\/i.ytimg.com\/vi\/07mLKtiiyBc\/maxresdefault.jpg\" alt=\"\"><\/img>\n\t\t\t\t\t<div class=\"uael-video__play-icon uael-animation-\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-play-circle\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c67ad59\" data-id=\"c67ad59\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-61111f5 uael-aspect-ratio-16_9 uael-youtube-subscribe-no elementor-widget elementor-widget-uael-video\" data-id=\"61111f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"uael-video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-video__outer-wrap  uael-video-type-youtube uael-video-play-lightbox\" data-device=\"false\" data-vsticky=\"no\" data-hidedesktop=\"\" data-hidetablet=\"\" data-hidemobile=\"\" data-vsticky-viewport=\"0\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox=\"{&quot;type&quot;:&quot;video&quot;,&quot;videoType&quot;:&quot;youtube&quot;,&quot;url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/embed\\\/n1vv-ZY2G1w?rel=0&amp;start&amp;end&amp;controls=1&amp;mute=0&amp;modestbranding=0&amp;&quot;,&quot;modalOptions&quot;:{&quot;id&quot;:&quot;elementor-lightbox-61111f5&quot;,&quot;entranceAnimation&quot;:&quot;&quot;,&quot;entranceAnimation_tablet&quot;:&quot;&quot;,&quot;entranceAnimation_mobile&quot;:&quot;&quot;,&quot;videoAspectRatio&quot;:&quot;169&quot;}}\">\n\t\t\t\t\t\t<div class=\"uael-video-inner-wrap\">\n\t\t\t\t<div class=\"uael-video__play\" data-src=\"https:\/\/www.youtube.com\/embed\/n1vv-ZY2G1w?rel=0&amp;start&amp;end&amp;controls=1&amp;mute=0&amp;modestbranding=0&amp;\">\n\t\t\t\t\t<img decoding=\"async\" class=\"uael-video__thumb\" src=\"https:\/\/i.ytimg.com\/vi\/n1vv-ZY2G1w\/maxresdefault.jpg\" alt=\"\"><\/img>\n\t\t\t\t\t<div class=\"uael-video__play-icon uael-animation-\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-play-circle\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Low Back Pain: Statistics, Symptoms, Causes &amp; Treatment \u00a0 Low back pain Statistics Low back pain is very common and about 80% of adults will experience it at some point in their lifetime. Back pain is usually due to poor body mechanics and can happen abruptly from an injury or over time.\u00a0 Causes of Low [&hellip;]<\/p>\n","protected":false},"author":2447,"featured_media":0,"parent":0,"menu_order":172,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_analytify_skip_tracking":false,"footnotes":""},"class_list":["post-178","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/advancedsofttissuerelease.com\/es\/wp-json\/wp\/v2\/pages\/178","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/advancedsofttissuerelease.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/advancedsofttissuerelease.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/advancedsofttissuerelease.com\/es\/wp-json\/wp\/v2\/users\/2447"}],"replies":[{"embeddable":true,"href":"https:\/\/advancedsofttissuerelease.com\/es\/wp-json\/wp\/v2\/comments?post=178"}],"version-history":[{"count":0,"href":"https:\/\/advancedsofttissuerelease.com\/es\/wp-json\/wp\/v2\/pages\/178\/revisions"}],"wp:attachment":[{"href":"https:\/\/advancedsofttissuerelease.com\/es\/wp-json\/wp\/v2\/media?parent=178"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}