{"id":102,"date":"2015-07-22T23:56:34","date_gmt":"2015-07-23T05:56:34","guid":{"rendered":"https:\/\/advancedsofttissuerelease.com\/tmj-1\/"},"modified":"2022-02-20T19:49:03","modified_gmt":"2022-02-21T02:49:03","slug":"temporomandibular-joint-tmj-disorder-tmd-definition-function-symptoms-causes-treatment","status":"publish","type":"page","link":"https:\/\/advancedsofttissuerelease.com\/it\/temporomandibular-joint-tmj-disorder-tmd-definition-function-symptoms-causes-treatment\/","title":{"rendered":"Disturbo dell&#039;articolazione temporo-mandibolare (ATM): definizione, funzione, sintomi, cause e trattamento"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"102\" class=\"elementor elementor-102\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-760c74f2 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"760c74f2\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6203e4a4\" data-id=\"6203e4a4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-683809d7 elementor-widget elementor-widget-text-editor\" data-id=\"683809d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1><span style=\"color: #696969;\"><span style=\"font-family: verdana,geneva,sans-serif;\"><strong><span style=\"font-size: 36px;\">Disturbo dell&#039;articolazione temporo-mandibolare (ATM): definizione, funzione, sintomi, cause e trattamento<\/span><\/strong><\/span><\/span><\/h1><div><span style=\"color: #696969;\"><span style=\"font-family: verdana,geneva,sans-serif;\"><strong><span style=\"font-size: 36px;\">\u00a0<\/span><\/strong><\/span><\/span><\/div><h2><strong><span style=\"color: #696969;\"><span style=\"font-family: verdana,geneva,sans-serif;\">Cos&#039;\u00e8 t<\/span><\/span><span style=\"caret-color: #696969; color: #696969; font-family: verdana, geneva, sans-serif;\">articolazione emporomandibolare (ATM)?<\/span><\/strong><\/h2><p><span style=\"color: #696969;\"><span style=\"font-family: verdana,geneva,sans-serif;\">Una delle articolazioni pi\u00f9 utilizzate nel corpo umano \u00e8 l&#039;articolazione temporo-mandibolare, comunemente abbreviata in ATM. Questa articolazione si trova su entrambi i lati del viso davanti alle orecchie, dove l&#039;osso mascellare inferiore (chiamato mandibola) incontra il cranio in corrispondenza delle ossa temporali.\u00a0<\/span><\/span><\/p><h2><strong><span style=\"color: #696969;\"><span style=\"font-family: verdana,geneva,sans-serif;\">Funzione del\u00a0<\/span><\/span><span style=\"font-family: 'Open Sans', verdana; font-size: 17px; color: #696969;\"><span style=\"font-family: verdana, geneva, sans-serif;\">T<\/span><\/span><span style=\"font-size: 17px; caret-color: #696969; color: #696969; font-family: verdana, geneva, sans-serif;\">Articolazione emporomandibolare (ATM)<\/span><\/strong><\/h2><p><span style=\"color: #696969;\"><span style=\"font-family: verdana,geneva,sans-serif;\">Facilita masticare, parlare, sbadigliare e fare espressioni facciali; essenzialmente tutto ci\u00f2 che comporta l&#039;apertura e la chiusura della bocca, che pu\u00f2 verificarsi fino a 2.000 volte al giorno! Gli studi hanno scoperto che pi\u00f9 di 25% della popolazione soffre di qualche tipo di disturbo dell&#039;ATM o dolore intorno alla mascella che porta a una disfunzione nel movimento della mascella. Se non trattato, il disturbo dell&#039;ATM pu\u00f2 portare a mal di testa, emicrania, dolore al collo e mal di schiena.\u00a0<\/span><\/span><\/p><h2><span style=\"color: #696969;\"><span style=\"font-family: verdana,geneva,sans-serif;\"><strong><span style=\"font-size: 24px;\">I sintomi del disturbo dell&#039;ATM<\/span><\/strong><\/span><\/span><\/h2><p><span style=\"color: #696969;\"><span style=\"font-family: verdana,geneva,sans-serif;\">I sintomi comuni del disturbo dell&#039;ATM includono:\u00a0<\/span><\/span><\/p><ol style=\"margin-left: 120px;\"><li><span style=\"color: #696969;\"><span style=\"font-family: verdana,geneva,sans-serif;\">Difficolt\u00e0 o dolore a masticare, parlare o sbadigliare<\/span><\/span><\/li><li><span style=\"color: #696969;\"><span style=\"font-family: verdana,geneva,sans-serif;\">Mal di testa<\/span><\/span><\/li><li><span style=\"color: #696969;\"><span style=\"font-family: verdana,geneva,sans-serif;\">Dolore al collo<\/span><\/span><\/li><li><span style=\"color: #696969;\"><span style=\"font-family: verdana,geneva,sans-serif;\">Alterazione del morso (il modo in cui i denti superiori e inferiori si uniscono)<\/span><\/span><\/li><li><span style=\"color: #696969;\"><span style=\"font-family: verdana,geneva,sans-serif;\">Serraggio o digrignamento cosciente o inconscio dei denti<\/span><\/span><\/li><li><span style=\"color: #696969;\"><span style=\"font-family: verdana,geneva,sans-serif;\">Sensazioni di clic, bloccaggio o scoppio quando si apre o si chiude la mascella<\/span><\/span><\/li><li><span style=\"color: #696969;\"><span style=\"font-family: verdana,geneva,sans-serif;\">Dolore o ronzio nelle orecchie (tennite) o sensazione di pienezza nelle orecchie<\/span><\/span><\/li><li><span style=\"color: #696969;\"><span style=\"font-family: verdana,geneva,sans-serif;\">Ridotta capacit\u00e0 di aprire la bocca<\/span><\/span><\/li><li><span style=\"color: #696969;\"><span style=\"font-family: verdana,geneva,sans-serif;\">Dolore o tenerezza intorno al viso, all&#039;articolazione della mascella, al collo o alle orecchie, specialmente quando si mastica, si parla o si apre la bocca<\/span><\/span><\/li><\/ol><h2><span style=\"color: #696969;\"><span style=\"font-family: verdana,geneva,sans-serif;\"><strong><span style=\"font-size: 24px;\">Cause del disturbo dell&#039;ATM<\/span><\/strong><\/span><\/span><\/h2><p><span style=\"color: #696969;\"><span style=\"font-family: verdana,geneva,sans-serif;\">Alcune cause o aggravanti del disturbo dell&#039;ATM includono:<\/span><\/span><\/p><ol><li><span style=\"color: #696969;\"><span style=\"font-family: verdana,geneva,sans-serif;\">Lesione traumatica alla mascella, all&#039;ATM, ai muscoli associati, alla testa o al collo<\/span><\/span><\/li><li><span style=\"color: #696969;\"><span style=\"font-family: verdana,geneva,sans-serif;\">Restrizione miofasciale in uno dei muscoli della mascella, come il massetere, che provoca dolore quando la mascella si muove<\/span><\/span><\/li><li><span style=\"color: #696969;\"><span style=\"font-family: verdana,geneva,sans-serif;\">Qualsiasi interruzione dell&#039;articolazione dovuta a lussazione della mascella, dislocazione del disco o lesione del condilo<\/span><\/span><\/li><li><span style=\"color: #696969;\"><span style=\"font-family: verdana,geneva,sans-serif;\">Artrite dell&#039;ATM<\/span><\/span><\/li><li><span style=\"color: #696969;\"><span style=\"font-family: verdana,geneva,sans-serif;\">Stress che crea ulteriore tensione nella mascella e nei muscoli facciali<\/span><\/span><\/li><li><span style=\"color: #696969;\"><span style=\"font-family: verdana,geneva,sans-serif;\">Qualsiasi procedura odontoiatrica che modifichi il proprio morso (ortodonzia, studi dentistici, ecc.)<\/span><\/span><\/li><\/ol><h2><span style=\"color: #696969;\"><span style=\"font-family: verdana,geneva,sans-serif;\"><strong><span style=\"font-size: 24px;\">Trattamento per il disturbo dell&#039;ATM<\/span><\/strong><\/span><\/span><\/h2><p><span style=\"color: #696969;\"><span style=\"font-family: verdana,geneva,sans-serif;\">ASTR<sup style=\"font-family: 'trebuchet ms', helvetica, sans-serif;\"><span style=\"font-size: 13.3333px;\">\u00a0<\/span><\/sup>\u00e8 una specialit\u00e0 di terapia manuale delicata che eccelle nel trattamento del dolore dell&#039;ATM e ottiene risultati a lungo termine perch\u00e9 mira alla fonte del dolore senza farmaci, interventi chirurgici o dolore aggiuntivo. Il trattamento ASTR pu\u00f2 essere eseguito per il disturbo dell&#039;ATM<\/span><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-27fa048 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"27fa048\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a4f6e66\" data-id=\"a4f6e66\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1da528e uael-heading-align-center elementor-widget elementor-widget-uael-advanced-heading\" data-id=\"1da528e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"uael-advanced-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"uael-module-content uael-heading-wrapper\">\n\t\t\t\t\t\t\n\t\t\t<h1 class=\"uael-heading\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-heading-text elementor-inline-editing uael-size--default\" data-elementor-setting-key=\"heading_title\" data-elementor-inline-editing-toolbar=\"basic\">Trattamento domiciliare del disturbo dell&#039;articolazione temporo-mandibolare (ATM).<\/span>\n\t\t\t\t\t\t\t<\/h1>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2cbe4f3 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2cbe4f3\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-332bc57\" data-id=\"332bc57\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-db89bb9 uael-aspect-ratio-16_9 uael-youtube-subscribe-no elementor-widget elementor-widget-uael-video\" data-id=\"db89bb9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"uael-video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-video__outer-wrap  uael-video-type-youtube uael-video-play-lightbox\" data-device=\"false\" data-vsticky=\"no\" data-hidedesktop=\"\" data-hidetablet=\"\" data-hidemobile=\"\" data-vsticky-viewport=\"0\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox=\"{&quot;type&quot;:&quot;video&quot;,&quot;videoType&quot;:&quot;youtube&quot;,&quot;url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/embed\\\/EWL3NHpDQQI?rel=0&amp;start&amp;end&amp;controls=1&amp;mute=0&amp;modestbranding=0&amp;&quot;,&quot;modalOptions&quot;:{&quot;id&quot;:&quot;elementor-lightbox-db89bb9&quot;,&quot;entranceAnimation&quot;:&quot;&quot;,&quot;entranceAnimation_tablet&quot;:&quot;&quot;,&quot;entranceAnimation_mobile&quot;:&quot;&quot;,&quot;videoAspectRatio&quot;:&quot;169&quot;}}\">\n\t\t\t\t\t\t<div class=\"uael-video-inner-wrap\">\n\t\t\t\t<div class=\"uael-video__play\" data-src=\"https:\/\/www.youtube.com\/embed\/EWL3NHpDQQI?rel=0&amp;start&amp;end&amp;controls=1&amp;mute=0&amp;modestbranding=0&amp;\">\n\t\t\t\t\t<img decoding=\"async\" class=\"uael-video__thumb\" src=\"https:\/\/i.ytimg.com\/vi\/EWL3NHpDQQI\/maxresdefault.jpg\" alt=\"\"><\/img>\n\t\t\t\t\t<div class=\"uael-video__play-icon uael-animation-\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-play-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zm115.7 272l-176 101c-15.8 8.8-35.7-2.5-35.7-21V152c0-18.4 19.8-29.8 35.7-21l176 107c16.4 9.2 16.4 32.9 0 42z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4cbf7f9\" data-id=\"4cbf7f9\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1751944 elementor-widget elementor-widget-heading\" data-id=\"1751944\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/advancedsofttissuerelease.com\/treat-your-pain-at-home-2\/\">Trattare il tuo dolore a casa<\/a><\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-320a7dd elementor-align-end elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"320a7dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-smile\" viewbox=\"0 0 496 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M248 8C111 8 0 119 0 256s111 248 248 248 248-111 248-248S385 8 248 8zm0 448c-110.3 0-200-89.7-200-200S137.7 56 248 56s200 89.7 200 200-89.7 200-200 200zm-80-216c17.7 0 32-14.3 32-32s-14.3-32-32-32-32 14.3-32 32 14.3 32 32 32zm160 0c17.7 0 32-14.3 32-32s-14.3-32-32-32-32 14.3-32 32 14.3 32 32 32zm4 72.6c-20.8 25-51.5 39.4-84 39.4s-63.2-14.3-84-39.4c-8.5-10.2-23.7-11.5-33.8-3.1-10.2 8.5-11.5 23.6-3.1 33.8 30 36 74.1 56.6 120.9 56.6s90.9-20.6 120.9-56.6c8.5-10.2 7.1-25.3-3.1-33.8-10.1-8.4-25.3-7.1-33.8 3.1z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Risultati rapidi<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"auxicon auxicon-zap\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Il trattamento richiede circa 5 minuti al giorno<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"auxicon auxicon-thumbs-up\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Strumenti medici facili da usare<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-check-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119.033 8 8 119.033 8 256s111.033 248 248 248 248-111.033 248-248S392.967 8 256 8zm0 48c110.532 0 200 89.451 200 200 0 110.532-89.451 200-200 200-110.532 0-200-89.451-200-200 0-110.532 89.451-200 200-200m140.204 130.267l-22.536-22.718c-4.667-4.705-12.265-4.736-16.97-.068L215.346 303.697l-59.792-60.277c-4.667-4.705-12.265-4.736-16.97-.069l-22.719 22.536c-4.705 4.667-4.736 12.265-.068 16.971l90.781 91.516c4.667 4.705 12.265 4.736 16.97.068l172.589-171.204c4.704-4.668 4.734-12.266.067-16.971z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Approccio olistico naturale<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"auxicon auxicon-search-5\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Trattare la causa principale del problema<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-user-md\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224 256c70.7 0 128-57.3 128-128S294.7 0 224 0 96 57.3 96 128s57.3 128 128 128zM104 424c0 13.3 10.7 24 24 24s24-10.7 24-24-10.7-24-24-24-24 10.7-24 24zm216-135.4v49c36.5 7.4 64 39.8 64 78.4v41.7c0 7.6-5.4 14.2-12.9 15.7l-32.2 6.4c-4.3.9-8.5-1.9-9.4-6.3l-3.1-15.7c-.9-4.3 1.9-8.6 6.3-9.4l19.3-3.9V416c0-62.8-96-65.1-96 1.9v26.7l19.3 3.9c4.3.9 7.1 5.1 6.3 9.4l-3.1 15.7c-.9 4.3-5.1 7.1-9.4 6.3l-31.2-4.2c-7.9-1.1-13.8-7.8-13.8-15.9V416c0-38.6 27.5-70.9 64-78.4v-45.2c-2.2.7-4.4 1.1-6.6 1.9-18 6.3-37.3 9.8-57.4 9.8s-39.4-3.5-57.4-9.8c-7.4-2.6-14.9-4.2-22.6-5.2v81.6c23.1 6.9 40 28.1 40 53.4 0 30.9-25.1 56-56 56s-56-25.1-56-56c0-25.3 16.9-46.5 40-53.4v-80.4C48.5 301 0 355.8 0 422.4v44.8C0 491.9 20.1 512 44.8 512h358.4c24.7 0 44.8-20.1 44.8-44.8v-44.8c0-72-56.8-130.3-128-133.8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Inventato da un medico che aveva dolore cronico<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/advancedsofttissuerelease.com\/what-is-astr\/research\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"auxicon auxicon-book-open\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Sostenuto da oltre 45 studi<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-216ee3a elementor-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"216ee3a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/advancedsofttissuerelease.com\/treat-your-pain-at-home-2\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Inizia il tuo viaggio di guarigione oggi<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dc720ed elementor-widget elementor-widget-heading\" data-id=\"dc720ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/advancedsofttissuerelease.com\/product\/treat-your-pain-at-home-payment-plan\/\">Piani di pagamento disponibili<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1f66436 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1f66436\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-93cf855\" data-id=\"93cf855\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-acb13dd elementor-widget elementor-widget-heading\" data-id=\"acb13dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ASTR eccezionalmente diverso<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-12ee42b elementor-widget elementor-widget-text-editor\" data-id=\"12ee42b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Recensioni raccolte da vari siti web<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aaed209 elementor-star-rating--align-center elementor--star-style-star_fontawesome elementor-widget elementor-widget-star-rating\" data-id=\"aaed209\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"star-rating.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-star-rating__wrapper\">\n\t\t\t\t\t\t<div class=\"elementor-star-rating\" itemtype=\"http:\/\/schema.org\/Rating\" itemscope=\"\" itemprop=\"reviewRating\">\n\t\t\t\t<i class=\"elementor-star-full\" aria-hidden=\"true\">\ue934<\/i><i class=\"elementor-star-full\" aria-hidden=\"true\">\ue934<\/i><i class=\"elementor-star-full\" aria-hidden=\"true\">\ue934<\/i><i class=\"elementor-star-full\" aria-hidden=\"true\">\ue934<\/i><i class=\"elementor-star-full\" aria-hidden=\"true\">\ue934<\/i>\t\t\t\t<span itemprop=\"ratingValue\" class=\"elementor-screen-only\" data-no-translation=\"\" data-trp-gettext=\"\">\u05d3\u05d5\u05e8\u05d2 5 \u05de\u05ea\u05d5\u05da 5<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-28c8047 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"28c8047\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/advancedsofttissuerelease.com\/treatment-videos-2\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Guarda i video del trattamento e del follow-up<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2d163f1 elementor-testimonial--skin-default elementor-testimonial--layout-image_inline elementor-testimonial--align-center elementor-arrows-yes elementor-pagination-type-bullets elementor-widget elementor-widget-testimonial-carousel\" data-id=\"2d163f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_per_view&quot;:&quot;3&quot;,&quot;show_arrows&quot;:&quot;yes&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;speed&quot;:500,&quot;loop&quot;:&quot;yes&quot;,&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]}}\" data-widget_type=\"testimonial-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"\u05e1\u05dc\u05d9\u05d9\u05d3\u05d9\u05dd\" data-no-translation-aria-label=\"\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"Ho avuto problemi con il peggioramento degli effetti della spondilite anchilosante (artrite della colonna vertebrale, mal di schiena). Dopo aver avuto <b>ha vissuto con la malattia per oltre 40 anni<\/b>Ero scettico sul fatto che qualsiasi sollievo sarebbe stato possibile. Con mio grande stupore, ho sperimentato\u00a0<b>sollievo immediato dopo una sessione<\/b>. Sono molto riconoscente per il lavoro che fate\".\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">William K<\/span><span class=\"elementor-testimonial__title\">Dolore alla schiena<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"Dopo aver <b>18 mesi di terapia fisica tradizionale dopo due interventi al ginocchio<\/b> per sostituire il mio legamento crociato anteriore, ero scettico che qualcosa di pi\u00f9 potesse essere fatto per aiutare il mio dolore e la rigidit\u00e0 del ginocchio.\u00a0<b>Dopo una sola visita<\/b>Sono rimasto sbalordito dai risultati che il Dottor Jacobs \u00e8 stato in grado di produrre con la sua tecnica Advanced Soft Tissue Release! .... Sono rimasto molto colpito da come il mio ginocchio ha risposto e si \u00e8 sciolto, soprattutto perch\u00e9 sono passati due anni dal mio intervento originale.\u00a0<b>Sono entrato come scettico e ora sono un credente!<\/b>\"\u00a0\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Mychal T<\/span><span class=\"elementor-testimonial__title\">Dolore al ginocchio<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"Per <b>un anno<\/b>Non riuscivo ad aprire la mano. Il mio pollice aveva un movimento molto limitato senza molto dolore. Era difficile sollevare qualcosa, anche piccolo, o muovere la mano in un certo modo senza dolore. L'anno scorso ho fatto due iniezioni nella zona per la gestione del dolore. E prima ancora,<b> Ho fatto circa 5-6 mesi di chiropratica, ma il dolore tornava sempre<\/b>. A partire da oggi, ho avuto <b>3 trattamenti ASTR<\/b>. Posso aprire completamente la mano e non sento alcun dolore. <b>ASTR funziona! Senza dubbio, funziona!<\/b>\"\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Carol<\/span><span class=\"elementor-testimonial__title\">Dolore alla mano<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"Insieme al <b>eliminazione dei farmaci<\/b>.\u00a0<b>La tecnica ASTR ha ridotto enormemente la frequenza e l'intensit\u00e0 delle mie emicranie<\/b>\"\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Jessica Y<\/span><span class=\"elementor-testimonial__title\">Emicranie<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"Ho\u00a0<b>recuperato rapidamente<\/b>\u00a0Grazie al dottor Jacobs, il mio dolore non solo \u00e8 diminuito significativamente, ma \u00e8 stato eliminato completamente. La tecnica ASTR del dottor Jacob funziona rapidamente. La cosa che preferisco \u00e8 che \u00e8\u00a0<b>senza dolore<\/b>. Raccomanderei sicuramente la sua terapia a chiunque conosca con dolore cronico\".\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Candace P<\/span><span class=\"elementor-testimonial__title\">Dolore alla mascella<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"Sono stato in grado di riprendere tutte le mie normali attivit\u00e0 dopo il suo trattamento e il\u00a0<b>il mal di testa non \u00e8 tornato<\/b>.\"\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Jeremy R<\/span><span class=\"elementor-testimonial__title\">Mal di testa<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"Ho avuto uno strappo muscolare all'avambraccio e al bicipite. Avevo un range di movimento limitato, non ero in grado di dormire e non ero in grado di estendere il mio braccio. Dopo <b>3 sessioni<\/b>, sono stato <b>senza dolore<\/b>. E dopo la mia quarta sessione avevo di nuovo una gamma completa di movimento, ero in grado di dormire, e sto effettivamente tornando indietro e iniziando ad allenarmi. <b>Sono molto contento della terapia e dei risultati!<\/b>\"\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Kathy<\/span><span class=\"elementor-testimonial__title\">Dolore al gomito<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"Stavo avendo <b>mal di testa circa 50% del tempo<\/b> da diversi mesi. Dopo diversi trattamenti i miei mal di testa hanno cominciato a diminuire e <b>Non ho pi\u00f9 mal di testa da un paio di mesi<\/b>. \u00c8 meraviglioso non avere dolore\".\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Liz S<\/span><span class=\"elementor-testimonial__title\">Mal di testa<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"Sono nel settore della terapia fisica da oltre 3 anni. 6 mesi fa ho iniziato a lavorare con il Dr. Jacobs e devo dire che <b>Non sono mai stato testimone di un tasso di recupero dei pazienti cos\u00ec positivo come qui.<\/b>.  Il dottor Joseph Jacobs sa sicuramente come arrivare alla radice del disturbo dei pazienti con i suoi strumenti e metodi brevettati di terapia fisica. <b>All'inizio ero scettico, ma dopo aver assistito ripetutamente al recupero dei pazienti, sono arrivato a credere nella sua pratica.<\/b>. Sono orgoglioso di far parte dell'aiuto ai pazienti nel loro recupero\".\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Dee Ann Pope<\/span><span class=\"elementor-testimonial__title\">Collega precedente<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"Avevo dei brutti mal di testa quasi tutti i giorni dopo il lavoro. Dopo solo il <b>prima visita<\/b> i miei mal di testa erano spariti e <b>non sono tornati<\/b>\"\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Drew A<\/span><span class=\"elementor-testimonial__title\">Mal di testa<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"Per il passato <b>anno<\/b>Mi stavo intorpidendo e stringendo il piede. L'intorpidimento era orribile e non sapevo cosa fare. Dopo 7 trattamenti ASTR, <b>ora non sento alcun dolore<\/b>. \u00c8 stato tutto molto confortevole\".\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Richard<\/span><span class=\"elementor-testimonial__title\">Dolore al piede<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"Sono entrato con l'ATM, un'ampiezza di movimento limitata e dolore al collo e alle spalle (con un dolore lancinante sopra l'orecchio destro). Dopo appena\u00a0<b>un trattamento<\/b>il mio collo e le mie spalle hanno <b>sollievo immediato!<\/b> Dopo 3 trattamenti, il mio dolore acuto sopra l'orecchio era sparito. Sono sicuro che con \"Advanced Soft Tissue Release\" e la mia diligenza nel seguire il programma di esercizi fornito, mi sentir\u00f2 presto come nuovo\".\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Margarete E<\/span><span class=\"elementor-testimonial__title\">Dolore alla mascella<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"Prima del trattamento, avevo un range di movimento molto limitato quando giravo il collo da un lato all'altro o mi piegavo in avanti. Dopo un trattamento, ho sentito un rilascio e ho potuto piegare e girare il collo con meno stress. Il trattamento \u00e8 stato <b>senza dolore<\/b>, non invasivo e migliore di qualsiasi massaggio che abbia mai avuto!\"\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Cathy<\/span><span class=\"elementor-testimonial__title\">Dolore al collo<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"<b>Mi sono sentito di nuovo normale dopo circa una settimana<\/b>. Il mio polso ha quasi recuperato tutta la sua gamma di movimento dopo due settimane e il dolore si \u00e8 ridotto sostanzialmente. <b>Consiglio vivamente ASTR a chiunque.<\/b>\"\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Alex B<\/span><span class=\"elementor-testimonial__title\">Dolore alla schiena e al polso<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"Ho avuto uno spasmo al collo tre giorni fa e non potevo muovere il collo. Il mio collo era rigido e la mia spalla era davvero insensibile. Ora ho quasi <b>nessun dolore<\/b>. Ho avuto <b>tre trattamenti<\/b> e ora posso muovere il collo\".\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Anthony<\/span><span class=\"elementor-testimonial__title\">Dolore al collo<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\" <b>\u00c8 stato un processo frustrante ricevere 3 mesi di terapia fisica, 2 iniezioni di cortisone e 3 diversi plantari con un sollievo minimo<\/b>....Grazie mille Dr. Jacobs per aver alleviato il mio <b>dolore da fascite plantare cronica<\/b>. Ho deciso di seguire tutto il programma e in appena <b>3 visite<\/b> Sono stato in grado di camminare per 3 miglia senza dolore, lei sa il fatto suo ed \u00e8 stato molto intelligente a inventare strumenti e trattamenti ASTR. Spero che altri medici imparino da voi\".\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Elsie J<\/span><span class=\"elementor-testimonial__title\">Fascite plantare<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"Ho sofferto di dolori cronici al collo, alle spalle e alle ginocchia a causa della fibromialgia negli ultimi <b>12 anni<\/b>.<b> Ho provato il massaggio, la fisioterapia, la chiropratica e i farmaci ma continuo a provare dolore<\/b>. Dopo aver seguito il piano alimentare del Dr. Jacobs, la modifica del comportamento, l'ergonomia e le raccomandazioni degli integratori, il mio <b>i sintomi della fibromialgia \u00e8 stato diminuito da 90%<\/b>.\"\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\"> Liam M<\/span><span class=\"elementor-testimonial__title\">Fibromialgia, dolore al collo, alle spalle e alle ginocchia<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"Una tecnica incredibile ha funzionato per aiutarmi a rompere il tessuto cicatriziale nella mia mascella, nel collo, nello stomaco e dopo l'intervento di protesi al seno. <b> Sono incredibilmente fuori dal dolore<\/b>\"\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Janice Salmon<\/span><span class=\"elementor-testimonial__title\">Dolori alla mascella, al collo e allo stomaco<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"Ho visto il dottor Jacobs 3 anni fa per <b>mal di testa da tensione quotidiano<\/b>.  Ero infelice e prendevo <b>Advil tutti i giorni<\/b>.  Dopo diversi trattamenti, il tessuto cicatriziale che non mi ero nemmeno reso conto di avere sulla testa e sul collo ha finalmente cominciato a scomparire.  Dopo circa 6 settimane, <b>Non avevo pi\u00f9 mal di testa<\/b>.  Ancora oggi non lo so!  Grazie!\"\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Melissa K<\/span><span class=\"elementor-testimonial__title\">Mal di testa<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"Il <b>Strumenti ASTR<\/b> sono stati <b>estremamente utile<\/b> nel prevenire i miei mal di testa o emicranie quando li sento arrivare, cos\u00ec come i muscoli tesi e altri dolori\".\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Stacy H<\/span><span class=\"elementor-testimonial__title\">Emicrania<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"Non \u00e8 la terapia fisica di tutti i giorni, hanno una comprensione del tuo corpo e un metodo di riabilitazione che non ho visto in altri posti. Consiglio vivamente questo posto perch\u00e9 sono amichevoli e fanno dei passi in pi\u00f9 per<b> aiutarvi a tornare fisicamente integri<\/b>.\"\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Maher S<\/span><span class=\"elementor-testimonial__title\">Dolore alla schiena<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"Ho fatto un trattamento per il mio neuroma di Morton per il quale soffrivo da 2 anni. Ho fatto un trattamento medico ma non \u00e8 cambiato nulla. Il medico mi ha chiesto di fare un'operazione. Io non volevo. I <b>ha volato 24 ore<\/b> per avere il trattamento del dottor Jacob: ne \u00e8 valsa davvero la pena. Dopo il <b>primo trattamento<\/b> il risultato era ovvio: <b>pi\u00f9 nessun dolore<\/b> e potrei indossare di nuovo le scarpe. <b>Semplicemente stupefacente! 2 settimane dopo, non c'\u00e8 pi\u00f9 traccia di dolore<\/b>. Il mio piede non fa pi\u00f9 male. Posso camminare e correre. Posso dormire una notte intera senza essere svegliato dal dolore. \u00c8 fantastico!\"\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Christine D<\/span><span class=\"elementor-testimonial__title\">Neuroma di Morton<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\" Il mio mal di schiena era presente da <b>7 anni<\/b> e dopo <b>un trattamento<\/b> Era come se fosse una nuova schiena. Ora posso muoverla correttamente e non c'\u00e8 pi\u00f9 dolore.\nIl trattamento \u00e8 davvero buono, incredibile!\".\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Christine D<\/span><span class=\"elementor-testimonial__title\">Dolore alla schiena e al collo<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"Ho avuto dolori alla schiena per pi\u00f9 di <b>5 anni<\/b>. Il mio mal di schiena stava peggiorando nell'ultimo anno, quindi <b>Ho provato la massoterapia, la cura chiropratica, la terapia fisica e i farmaci per il dolore, ma non ho provato sollievo<\/b>.....I cucire lui <b>due volte e il mio dolore \u00e8 completamente sparito<\/b>. Ora sono in grado di camminare, dormire e guidare senza mal di schiena. Sono un sostenitore del trattamento inventivo del Dr. Jacobs chiamato ASTR. Consiglio vivamente il trattamento ASTR per il dolore alla schiena o ai muscoli\".\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Shea G<\/span><span class=\"elementor-testimonial__title\">Dolore alla schiena<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\" Ho finalmente ottenuto sollievo dal mio dolore al ginocchio dopo essere andato dal Dr. Jacobs ..... Il suo approccio alla terapia fisica \u00e8 molto olistico. <b>Ho sprecato diversi mesi andando da medici tradizionali<\/b> che ha deciso che era la mia dieta o \"nella mia testa\" senza arrivare da nessuna parte prima di trovare il dottor Jacobs\".\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Norma F<\/span><span class=\"elementor-testimonial__title\">Dolore al ginocchio<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"...Entro un solo <b>pochi minuti<\/b> del mio primo trattamento, i livelli di dolore e di tensione nella mia mascella e nel collo sono passati da un 8 a un 2\".\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Tiffany A<\/span><span class=\"elementor-testimonial__title\">Dolore alla mascella<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\" Sto andando alla grande dopo un <b>sessioni di coppia<\/b> con il dottor Jacobs. Ho poco da <b>nessun dolore<\/b> ora. Che sollievo!  La mia esperienza con il dottor Jacobs \u00e8 stata fantastica. Grazie!\"\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Lola G<\/span><span class=\"elementor-testimonial__title\">Dolore alla schiena<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\" Ho sofferto di dolore all'articolazione SI negli ultimi <b> 2 anni<\/b>. Era cos\u00ec grave che ho dovuto smettere di ballare e mi sono dovuto anche trattenere per qualcosa di semplice come uno starnuto... Dopo appena un <b>poche visite<\/b>Ho potuto gi\u00e0 dire che la tecnica ASTR stava funzionando!\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Alexandra Gonzalez<\/span><span class=\"elementor-testimonial__title\">Dolore alla schiena<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"Non potevo camminare, guidare o sedermi. Con il <b>2 prima visita<\/b>Ho sentito un'enorme differenza, posso guidare e camminare, alla 3a settimana la mia schiena \u00e8 quasi normale\".\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Nayibe Rahim<\/span><span class=\"elementor-testimonial__title\">Sciatica<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"\u05d4\u05e7\u05d5\u05d3\u05dd\" data-no-translation-aria-label=\"\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"\u05d4\u05d1\u05d0\" data-no-translation-aria-label=\"\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3f1d321 elementor-widget elementor-widget-heading\" data-id=\"3f1d321\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/advancedsofttissuerelease.com\/product\/pain-relief-cream\/\">Crema antidolorifica<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a02908c elementor-widget elementor-widget-text-editor\" data-id=\"a02908c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><span style=\"color: #333333; font-size: medium;\"><span style=\"caret-color: #333333;\">Guarisci pi\u00f9 velocemente<\/span><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d050b4c elementor-align-center elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"d050b4c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/advancedsofttissuerelease.com\/product\/pain-relief-cream\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Acquista ora<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1cdbbd5 elementor-widget elementor-widget-image\" data-id=\"1cdbbd5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/advancedsofttissuerelease.com\/product\/pain-relief-cream\/\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/advancedsofttissuerelease.com\/wp-content\/uploads\/2022\/02\/ASTR-pain-relief-cream-decrease-inflammation-cream-wound-care-cream-eczema-Psoriasis-dermatitis--scaled-e1645656839627-300x300.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-33765\" alt=\"ASTR pain relief cream- decrease inflammation cream- wound care cream- eczema, Psoriasis, dermatitis\" srcset=\"https:\/\/advancedsofttissuerelease.com\/wp-content\/uploads\/2022\/02\/ASTR-pain-relief-cream-decrease-inflammation-cream-wound-care-cream-eczema-Psoriasis-dermatitis--scaled-e1645656839627-300x300.jpg 300w, https:\/\/advancedsofttissuerelease.com\/wp-content\/uploads\/2022\/02\/ASTR-pain-relief-cream-decrease-inflammation-cream-wound-care-cream-eczema-Psoriasis-dermatitis--scaled-e1645656839627-100x100.jpg 100w, https:\/\/advancedsofttissuerelease.com\/wp-content\/uploads\/2022\/02\/ASTR-pain-relief-cream-decrease-inflammation-cream-wound-care-cream-eczema-Psoriasis-dermatitis--scaled-e1645656839627-520x520.jpg 520w, https:\/\/advancedsofttissuerelease.com\/wp-content\/uploads\/2022\/02\/ASTR-pain-relief-cream-decrease-inflammation-cream-wound-care-cream-eczema-Psoriasis-dermatitis--scaled-e1645656839627-1200x1200.jpg 1200w, https:\/\/advancedsofttissuerelease.com\/wp-content\/uploads\/2022\/02\/ASTR-pain-relief-cream-decrease-inflammation-cream-wound-care-cream-eczema-Psoriasis-dermatitis--scaled-e1645656839627-768x768.jpg 768w, https:\/\/advancedsofttissuerelease.com\/wp-content\/uploads\/2022\/02\/ASTR-pain-relief-cream-decrease-inflammation-cream-wound-care-cream-eczema-Psoriasis-dermatitis--scaled-e1645656839627-1000x1000.jpg 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-475a96f elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"475a96f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-765c20d\" data-id=\"765c20d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8fb9602 uael-aspect-ratio-16_9 uael-youtube-subscribe-no elementor-widget elementor-widget-uael-video\" data-id=\"8fb9602\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"uael-video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-video__outer-wrap  uael-video-type-youtube uael-video-play-lightbox\" data-device=\"false\" data-vsticky=\"no\" data-hidedesktop=\"\" data-hidetablet=\"\" data-hidemobile=\"\" data-vsticky-viewport=\"0\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox=\"{&quot;type&quot;:&quot;video&quot;,&quot;videoType&quot;:&quot;youtube&quot;,&quot;url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/embed\\\/07mLKtiiyBc?rel=0&amp;start&amp;end&amp;controls=1&amp;mute=0&amp;modestbranding=0&amp;&quot;,&quot;modalOptions&quot;:{&quot;id&quot;:&quot;elementor-lightbox-8fb9602&quot;,&quot;entranceAnimation&quot;:&quot;&quot;,&quot;entranceAnimation_tablet&quot;:&quot;&quot;,&quot;entranceAnimation_mobile&quot;:&quot;&quot;,&quot;videoAspectRatio&quot;:&quot;169&quot;}}\">\n\t\t\t\t\t\t<div class=\"uael-video-inner-wrap\">\n\t\t\t\t<div class=\"uael-video__play\" data-src=\"https:\/\/www.youtube.com\/embed\/07mLKtiiyBc?rel=0&amp;start&amp;end&amp;controls=1&amp;mute=0&amp;modestbranding=0&amp;\">\n\t\t\t\t\t<img decoding=\"async\" class=\"uael-video__thumb\" src=\"https:\/\/i.ytimg.com\/vi\/07mLKtiiyBc\/maxresdefault.jpg\" alt=\"\"><\/img>\n\t\t\t\t\t<div class=\"uael-video__play-icon uael-animation-\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-play-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zm115.7 272l-176 101c-15.8 8.8-35.7-2.5-35.7-21V152c0-18.4 19.8-29.8 35.7-21l176 107c16.4 9.2 16.4 32.9 0 42z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6d38eb4\" data-id=\"6d38eb4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e90fb58 uael-aspect-ratio-16_9 uael-youtube-subscribe-no elementor-widget elementor-widget-uael-video\" data-id=\"e90fb58\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"uael-video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-video__outer-wrap  uael-video-type-youtube uael-video-play-lightbox\" data-device=\"false\" data-vsticky=\"no\" data-hidedesktop=\"\" data-hidetablet=\"\" data-hidemobile=\"\" data-vsticky-viewport=\"0\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox=\"{&quot;type&quot;:&quot;video&quot;,&quot;videoType&quot;:&quot;youtube&quot;,&quot;url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/embed\\\/n1vv-ZY2G1w?rel=0&amp;start&amp;end&amp;controls=1&amp;mute=0&amp;modestbranding=0&amp;&quot;,&quot;modalOptions&quot;:{&quot;id&quot;:&quot;elementor-lightbox-e90fb58&quot;,&quot;entranceAnimation&quot;:&quot;&quot;,&quot;entranceAnimation_tablet&quot;:&quot;&quot;,&quot;entranceAnimation_mobile&quot;:&quot;&quot;,&quot;videoAspectRatio&quot;:&quot;169&quot;}}\">\n\t\t\t\t\t\t<div class=\"uael-video-inner-wrap\">\n\t\t\t\t<div class=\"uael-video__play\" data-src=\"https:\/\/www.youtube.com\/embed\/n1vv-ZY2G1w?rel=0&amp;start&amp;end&amp;controls=1&amp;mute=0&amp;modestbranding=0&amp;\">\n\t\t\t\t\t<img decoding=\"async\" class=\"uael-video__thumb\" src=\"https:\/\/i.ytimg.com\/vi\/n1vv-ZY2G1w\/maxresdefault.jpg\" alt=\"\"><\/img>\n\t\t\t\t\t<div class=\"uael-video__play-icon uael-animation-\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-play-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zm115.7 272l-176 101c-15.8 8.8-35.7-2.5-35.7-21V152c0-18.4 19.8-29.8 35.7-21l176 107c16.4 9.2 16.4 32.9 0 42z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Temporomandibular Joint (TMJ) Disorder (TMD): Definition, Function, Symptoms, Causes &amp; Treatment \u00a0 What is Temporomandibular Joint (TMJ)? One of the most frequently used joints in the human body is the temporomandibular joint, commonly abbreviated as TMJ. This joint is located on both sides of the face in front of the ears, where the lower jaw [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":240,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_analytify_skip_tracking":false,"footnotes":""},"class_list":["post-102","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/advancedsofttissuerelease.com\/it\/wp-json\/wp\/v2\/pages\/102","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/advancedsofttissuerelease.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/advancedsofttissuerelease.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/advancedsofttissuerelease.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/advancedsofttissuerelease.com\/it\/wp-json\/wp\/v2\/comments?post=102"}],"version-history":[{"count":0,"href":"https:\/\/advancedsofttissuerelease.com\/it\/wp-json\/wp\/v2\/pages\/102\/revisions"}],"wp:attachment":[{"href":"https:\/\/advancedsofttissuerelease.com\/it\/wp-json\/wp\/v2\/media?parent=102"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}